{"id":2128,"date":"2016-07-18T07:12:21","date_gmt":"2016-07-18T07:12:21","guid":{"rendered":"http:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?page_id=2128"},"modified":"2016-07-18T07:13:04","modified_gmt":"2016-07-18T07:13:04","slug":"9-3-valor-usufructo-nuda-propiedad-titulo-html","status":"publish","type":"page","link":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/","title":{"rendered":"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo"},"content":{"rendered":"<p>La valoraci\u00f3n de t\u00edtulos procedentes de un empr\u00e9stito cualquiera implica conocer las cuant\u00edas de los derechos econ\u00f3micos futuros que dicho t\u00edtulo conlleva y actualizarlos al momento de estudio a un tipo adecuado (tanto de mercado).<\/p>\n<p>Definiciones:<\/p>\n<ul>\n<li> <span class=\"progress\">Valor de un t\u00edtulo<\/span> en el momento k (principios del per\u00edodo k+1), V<sub>k<\/sub>, es el resultado de actualizar al tanto de mercado (i<sub>m<\/sub>) todos los derechos econ\u00f3micos futuros que el t\u00edtulo conlleva.<\/li>\n<li> <span class=\"progress\">Usufructo de un t\u00edtulo<\/span> en el momento k (principios del per\u00edodo k+1), U<sub>k<\/sub>, es el resultado de actualizar al tanto de mercado (i<sub>m<\/sub>) todos los cupones futuros que el t\u00edtulo conlleva.<\/li>\n<li> <span class=\"progress\">Nuda propiedad de un t\u00edtulo<\/span> en el momento k (principios del per\u00edodo k+1), N<sub>k<\/sub> , es el resultado de actualizar al tanto de mercado (i<sub>m<\/sub>) el valor de reembolso del t\u00edtulo.<\/li>\n<\/ul>\n<p>De las definiciones anteriores se deduce la necesidad de conocer para estos c\u00e1lculos:<\/p>\n<ol class=\"lalpha\">\n<li> Cuant\u00eda de los derechos econ\u00f3micos futuros del t\u00edtulo (cupones, valor de reembolso y lotes).<\/li>\n<li> N\u00famero de capitales (derechos econ\u00f3micos) a considerar.<\/li>\n<\/ol>\n<p>El n\u00famero de derechos est\u00e1 en funci\u00f3n del tiempo que el t\u00edtulo est\u00e9 en circulaci\u00f3n, o sea, del momento en que resulte amortizado. Por ello debemos considerar un horizonte temporal para su estudio, pudi\u00e9ndose contemplar tres posibilidades:<\/p>\n<ol class=\"lalpha\">\n<li> Conocer de antemano el momento del sorteo del t\u00edtulo.<\/li>\n<li> Estimar un per\u00edodo de vida para el t\u00edtulo, tom\u00e1ndose como tal la vida media (o mediana) del conjunto de t\u00edtulos del empr\u00e9stito en la fecha de estudio.<\/li>\n<li> Considerar un valor medio, es decir, calcular un valor global para el conjunto del empr\u00e9stito y dividirlo proporcionalmente entre el n\u00famero de t\u00edtulos vivos en la fecha de estudio.<\/li>\n<\/ol>\n<p>Aplicaremos estos escenarios a los diferentes tipos de empr\u00e9stitos estudiados.<\/p>\n<h3>9.3.1. Empr\u00e9stitos clase I, tipo I, normal<\/h3>\n<p> Empr\u00e9stitos con t\u00e9rmino amortizativo constante y cup\u00f3n constante y vencido pagadero a los t\u00edtulos en circulaci\u00f3n en cada momento.<\/p>\n<p>La estructura del t\u00e9rmino amortizativo es la siguiente:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-01.png\" width=\"340\" height=\"53\" \/><\/p>\n<p>&nbsp;<\/p>\n<p> Se trata de realizar el c\u00e1lculo del valor, usufructo y nuda propiedad de un t\u00edtulo procedente de este empr\u00e9stito en un momento cualquiera considerando los posibles escenarios antes comentados.<\/p>\n<p class=\"progress\"> Caso 1: el t\u00edtulo resultar\u00e1 amortizado en el momento k+t<\/p>\n<p>Estamos suponiendo que se conoce con absoluta certeza el momento en que resultar\u00e1 amortizado el t\u00edtulo estudiado.<\/p>\n<p>Gr\u00e1ficamente el esquema de flujos pendientes desde la fecha de estudio (k) hasta el momento del sorteo (k + t): <\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-02.png\" width=\"506\" height=\"94\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando las definiciones de usufructo, nuda propiedad y valor:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-03.png\" width=\"270\" height=\"168\" \/><\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 25<\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 20.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n anual: 50 euros.<\/li>\n<li> Duraci\u00f3n: 4 a\u00f1os.<\/li>\n<li> Prima amortizaci\u00f3n: 200 euros.<\/li>\n<li> Anualidad constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li>  Valor, usufructo y nuda propiedad en el origen de un t\u00edtulo que resultar\u00e1 amortizado en el segundo sorteo, siendo el tanto de mercado el 4%.<\/li>\n<li> Valor, usufructo y nuda propiedad en el origen de un t\u00edtulo que resultar\u00e1 amortizado en el cuarto sorteo, siendo el tanto de mercado el 4%.<\/li>\n<\/ul>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p> a) Si el t\u00edtulo se amortiza en el segundo a\u00f1o:<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p535-01.png\" width=\"372\" height=\"191\" \/><\/p>\n<p>b) Si el t\u00edtulo se amortiza en el cuarto a\u00f1o:<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p535-02.png\" width=\"463\" height=\"55\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p536-01.png\" width=\"462\" height=\"126\" \/><\/p>\n<\/div>\n<p>&nbsp;  <\/p>\n<p class=\"progress\">Caso 2: tomando como estimaci\u00f3n la vida media del empr\u00e9stito en la fecha de estudio<\/p>\n<p> Ahora desconocemos el momento en que resultar\u00e1 amortizado el t\u00edtulo estudiado, por ello se toma como estimaci\u00f3n la vida media calculada para todo el empr\u00e9stito en la fecha donde estamos valorando.<\/p>\n<p> Gr\u00e1ficamente el esquema de flujos pendientes desde la fecha de estudio (k) hasta el momento del sorteo (k + V<sub>m<\/sub>): <\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p536-02.png\" width=\"509\" height=\"102\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando de nuevo las definiciones de usufructo, nuda propiedad y valor:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p536-03.png\" width=\"290\" height=\"171\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\"> Caso 3: considerando valores medios<\/p>\n<p> En los dos casos anteriores, bien conociendo la fecha del sorteo bien tomando como horizonte de estudio la vida media del empr\u00e9stito, se considera \u00fanicamente el t\u00edtulo objeto de valoraci\u00f3n. Ahora, por el contrario, se trabaja con el conjunto de t\u00edtulos vivos en la fecha de estudio del empr\u00e9stito, para, despu\u00e9s, estimar el valor medio de cada uno de ellos.<\/p>\n<p> El esquema de flujos pendientes del empr\u00e9stito en su conjunto es el siguiente:<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p537-01.png\" width=\"498\" height=\"141\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando las definiciones de usufructo, nuda propiedad y valor, en este caso aplicados para el conjunto del empr\u00e9stito (valores totales o globales):<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p537-02.png\" width=\"541\" height=\"217\" \/><\/p>\n<p>&nbsp;<\/p>\n<p> Estos valores globales se repartir\u00e1n entre el n\u00famero de t\u00edtulos vivos en la fecha de estudio (N<sub>k+1<\/sub>), para obtener los valores medios por t\u00edtulo de usufructo, nuda propiedad y valor:<\/p>\n<p>&nbsp; <\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p537-03.png\" width=\"504\" height=\"61\" \/><\/p>\n<p>&nbsp;  <\/p>\n<p> No obstante, este m\u00e9todo de c\u00e1lculo exige conocer las cantidades destinadas al pago de cupones y de amortizaci\u00f3n en cada momento desde la fecha de estudio hasta el final del empr\u00e9stito (cuadro de amortizaci\u00f3n). Un sistema alternativo ser\u00eda la utilizaci\u00f3n del siguiente sistema de ecuaciones, que solamente se podr\u00e1 emplear en el supuesto de que se cumplan los tres siguientes requisitos:<\/p>\n<ol>\n<li> El cup\u00f3n peri\u00f3dico se mantiene constante desde la fecha de estudio hasta n.<\/li>\n<li> El tanto de mercado (i<sub>m<\/sub>) sea diferente al tanto del cup\u00f3n (i).<\/li>\n<li> Encontrarse al principio de un per\u00edodo.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p538-01.png\" width=\"204\" height=\"123\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Donde: <\/p>\n<p> i: Tipo del cup\u00f3n del t\u00edtulo.<br \/>\n    i<sub>m<\/sub>: Tipo de mercado.<br \/>\n    c: Nominal del t\u00edtulo.<\/p>\n<p>Para su resoluci\u00f3n se calcular\u00e1 previamente el V<sub>k<\/sub>, seg\u00fan la expresi\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p538-02.png\" width=\"148\" height=\"56\" \/> <\/p>\n<p>&nbsp;<\/p>\n<p>y del sistema se despejar\u00e1n U<sub>k<\/sub> y N<sub>k<\/sub>.<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td><span class=\"progress\">Nota:<\/span> este sistema de ecuaciones tambi\u00e9n se puede aplicar a cualquier empr\u00e9stito de cup\u00f3n peri\u00f3dico con anualidad variable (clase I, tipo II).<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 26 <\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 30.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n anual: 100 euros.<\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Anualidad constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li>  Cuadro de amortizaci\u00f3n.<\/li>\n<li> Valor, usufructo y nuda propiedad en el origen a un tanto de mercado del 12%.<\/li>\n<\/ul>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p539-01.png\" width=\"290\" height=\"171\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p539-02.png\" width=\"356\" height=\"143\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress\">A\u00f1o \n    <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">T\u00edtulos vivos <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">T\u00edtulo amortiz. <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Total t\u00edt. amort. <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Intereses <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Amortizaci\u00f3n <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">T\u00e9rmino amortizativo<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1<br \/>\n  2<br \/>\n  3<\/div>\n<\/td>\n<td>\n<div align=\"right\">30.000<br \/>\n        20.937<br \/>\n      10.967<\/div>\n<\/td>\n<td>\n<div align=\"right\">9.063<br \/> <br \/>\n        9.970<br \/> <br \/>\n      10.967<\/div>\n<\/td>\n<td>\n<div align=\"right\">9.063<br \/> <br \/>\n        19.033<br \/> <br \/>\n      30.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">3.000.000<br \/> <br \/>\n      2.093.700<br \/> <br \/>\n      1.096.700<\/div>\n<\/td>\n<td>\n<div align=\"right\">9.063.000<br \/>\n      9.970.000<br \/> <br \/>\n      10.967.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">12.063.000<br \/>\n      12.063.700<br \/> <br \/>\n      12.063.700  <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad en el origen al tanto i<sub>m<\/sub> = 12%:<\/p>\n<p>1.\u00aa posibilidad: aplicando las definiciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p540-01.png\" width=\"479\" height=\"204\" \/> <\/p>\n<p>&nbsp;<\/p>\n<p>2.\u00aa posibilidad: aplicando el sistema de ecuaciones<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p540-02.png\" width=\"233\" height=\"113\" \/><\/p>\n<p>&nbsp;<\/p>\n<p> Aplicando la definici\u00f3n de valor medio de un t\u00edtulo se obtiene V<sub>o<\/sub>:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p541-01.png\" width=\"283\" height=\"58\" \/><\/p>\n<p>&nbsp;<\/p>\n<p> Del sistema se despeja la nuda propiedad y a continuaci\u00f3n el usufructo:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p541-03.png\" width=\"356\" height=\"36\" \/><\/p>\n<p align=\"center\">&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h3>  9.3.2. Incidencia de las distintas caracter\u00edsticas comerciales<\/h3>\n<p> Cuando existan en el empr\u00e9stito caracter\u00edsticas comerciales, ser\u00e1 preciso distinguir c\u00f3mo afectan a la hora de valorar el t\u00edtulo. Ser\u00e1 necesario, pues, un estudio individualizado de cada una de las posibles caracter\u00edsticas que pueden aparecer.<\/p>\n<p>De igual forma, se podr\u00e1 aplicar indistintamente las definiciones o aplicar el sistema de ecuaciones, si bien considerando c\u00f3mo afecta la(s) caracter\u00edstica(s) que en cada caso se presenten.<\/p>\n<p>Pasamos al estudio de cada caracter\u00edstica comercial:<\/p>\n<h4>9.3.2.1. Prima de amortizaci\u00f3n<\/h4>\n<p> Afecta a la nuda propiedad y al valor, pero no al usufructo.<\/p>\n<p>El sistema queda como sigue:<\/p>\n<p>&nbsp;<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p541-02.png\" width=\"241\" height=\"122\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Donde: <\/p>\n<p> i: Tipo del cup\u00f3n del t\u00edtulo.<br \/>\n    i<sub>m<\/sub>: Tipo de mercado.<br \/>\n    c: Nominal del t\u00edtulo.<br \/>\n    i&#8217;: Tipo normalizado del empr\u00e9stito.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 27<\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 1.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Inter\u00e9s anual: 6%.<\/li>\n<li> Duraci\u00f3n: 4 a\u00f1os.<\/li>\n<li> Valor de reembolso de los t\u00edtulos: 1.200 euros.<\/li>\n<li> Anualidad constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<p> Calcular el valor medio de un t\u00edtulo transcurrido 1 a\u00f1o desde la emisi\u00f3n, siendo el tanto de mercado el 7% efectivo anual.<\/p>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p542-01.png\" width=\"337\" height=\"170\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p543-03.png\" width=\"463\" height=\"273\" \/> <\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">C\u00e1lculo de los t\u00edtulos amortizados<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p543-04.png\" width=\"397\" height=\"168\" \/> <\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp; <\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\"><span class=\"progress\">&nbsp;<\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(1) <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(2) <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(3) <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(4) = (1) x 60 <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(5) = (2) x 1.200 <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(6) = (4) + (5)<\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">A\u00f1o \n      <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulos vivos <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulo amortiz. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Total t\u00edt. amort. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Intereses <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Amortizaci\u00f3n <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00e9rmino amortizativo<\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1<br \/>\n        2<br \/>\n        3<br \/>\n        4\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">1.000<br \/>\n        768<br \/>\n        524<br \/>\n        268\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">232<br \/>\n        244<br \/>\n        256<br \/>\n        268      <\/div>\n<\/td>\n<td>\n<div align=\"right\">232<br \/>\n        476<br \/>\n        732<br \/>\n        1.000    <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 60.000<br \/>\n         46.080<br \/>\n         31.440<br \/>\n        16.080<\/div>\n<\/td>\n<td>\n<div align=\"right\">278.400<br \/>\n        292.800<br \/>\n         307.200<br \/>\n        321.600<\/div>\n<\/td>\n<td>\n<div align=\"right\">338.400<br \/>\n         338.880<br \/>\n         338.640<br \/> <br \/>\n        337.680 <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad en 1 al tanto i<sub>m<\/sub> = 7%<\/p>\n<p> 1.\u00aa posibilidad: aplicando las definiciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p544-01.png\" width=\"430\" height=\"196\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>2.\u00aa posibilidad: aplicando el sistema de ecuaciones<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p544-02.png\" width=\"281\" height=\"109\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando la definici\u00f3n de valor medio de un t\u00edtulo se obtiene V<sub>1<\/sub>:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p544-03.png\" width=\"272\" height=\"60\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Del sistema se despeja la nuda propiedad y a continuaci\u00f3n el usufructo:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p544-04.png\" width=\"343\" height=\"32\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;  <\/p>\n<h4>9.3.2.2. Amortizaci\u00f3n seca<\/h4>\n<p> Afecta al usufructo y al valor, pero no a la nuda propiedad.<\/p>\n<p>El sistema de ecuaciones visto anteriormente considera que la amortizaci\u00f3n seca no es una p\u00e9rdida de cup\u00f3n sino una prima de amortizaci\u00f3n negativa, por lo que infravalora la nuda propiedad y da m\u00e1s valor al usufructo.<\/p>\n<p>Por este motivo, en lugar de aplicar el sistema se calcula el valor y la nuda propiedad aplicando las definiciones t\u00e9cnicas y el usufructo se obtiene por diferencias.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 28<\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 1.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Inter\u00e9s anual: 5%.<\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Los t\u00edtulos amortizados pierden el \u00faltimo cup\u00f3n.<\/li>\n<li> Anualidad constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<p>Calcular el valor medio de un t\u00edtulo transcurrido 1 a\u00f1o desde la emisi\u00f3n, siendo el tanto de mercado el 4% efectivo anual.<\/p>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p545-03.png\" width=\"392\" height=\"169\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p545-01.png\" width=\"241\" height=\"236\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">C\u00e1lculo de los t\u00edtulos amortizados <\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p545-02.png\" width=\"404\" height=\"144\" \/><\/p>\n<p class=\"progress\">&nbsp;<\/p>\n<p class=\"progress\">Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp; <\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\"><span class=\"progress\">&nbsp;<\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(1) <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(2) <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(3) <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(4) = [(1) \u2013 (2)] x 50<\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(5) = (2) x 1.200 <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">(6) = (4) + (5)<\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">A\u00f1o \n        <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulos vivos <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulo amortiz. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Total t\u00edt. amort. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Intereses <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Amortizaci\u00f3n <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00e9rmino amortizativo<\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1<br \/>\n        2<br \/>\n        3\n        <\/div>\n<\/td>\n<td>\n<div align=\"right\">1.000<br \/>\n        684<br \/>\n        351\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">316<br \/>\n         333<br \/>\n         351\n        <\/div>\n<\/td>\n<td>\n<div align=\"right\">316<br \/>\n         649<br \/>\n         1.000\n        <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 34.200<br \/>\n         17.550<\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\"> 316.000<br \/>\n         333.000<br \/>\n         351.000\n        <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 350.200<br \/>\n         350.550<br \/>\n        351.000\n        <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad en 1 al tanto i<sub>m<\/sub> = 4%<\/p>\n<p>1.\u00aa posibilidad: empleando los datos del cuadro<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p547-01.png\" width=\"356\" height=\"195\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>2.\u00aa posibilidad: aplicando las definiciones<\/p>\n<p>Aplicando la definici\u00f3n de valor medio de un t\u00edtulo se obtiene V<sub>1<\/sub>:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p547-02.png\" width=\"263\" height=\"67\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando la definici\u00f3n de nuda propiedad media se obtiene N<sub>1<\/sub>:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p547-03.png\" width=\"317\" height=\"53\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El usufructo se obtiene por diferencia entre valor y nuda propiedad: <\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p547-04.png\" width=\"304\" height=\"39\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h4>  9.3.2.3. Lotes<\/h4>\n<p> Afecta al valor, pero no al usufructo ni a la nuda propiedad.<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p548-01.png\" width=\"303\" height=\"121\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Donde el complemento es la actualizaci\u00f3n de los lotes futuros por obligaci\u00f3n en circulaci\u00f3n:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p548-02.png\" width=\"295\" height=\"100\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En este caso, previamente deberemos calcular el valor (por el mismo procedimiento) y el complemento aplicando su definici\u00f3n. Del sistema se despejar\u00e1n usufructo y nuda propiedad.<\/p>\n<h4> 9.3.2.4. Gastos de administraci\u00f3n<\/h4>\n<p> No afectan ni al usufructo ni a la nuda propiedad ni al valor.<\/p>\n<p>Hay que tener en cuenta que, de existir, los gastos de administraci\u00f3n forman parte de la anualidad del empr\u00e9stito, por lo que habr\u00e1 que quitarlos y a continuaci\u00f3n se utiliza el sistema de ecuaciones correspondiente.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 29<\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 30.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n anual: 100 euros.<\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Reparto de un premio de 200 euros a 1.000 t\u00edtulos amortizados cada a\u00f1o.<\/li>\n<li> Gastos de administraci\u00f3n del 1\u2030 de las cantidades pagadas.<\/li>\n<li> Todos los a\u00f1os se amortizan el mismo n\u00famero de t\u00edtulos.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li>  Cuadro de amortizaci\u00f3n.<\/li>\n<li> Valor, usufructo y nuda propiedad en el origen a un tanto de mercado del 12%.<\/li>\n<\/ul>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p549-01.png\" width=\"397\" height=\"114\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp; <\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress progress progress\">\n<div align=\"center\">A\u00f1o \n        <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress progress\">\n<div align=\"center\">T\u00edtulos vivos <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress progress\">\n<div align=\"center\">T\u00edtulo amortiz. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">Intereses<\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress progress\">\n<div align=\"center\" class=\"progress\">\n<div align=\"center\">Amortiz.<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">Lotes<\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">Gastos adm\u00f3n.<\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress progress\">\n<div align=\"center\">T\u00e9rmino amortizativo<\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1<br \/>\n        2<br \/>\n        3\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">30.000<br \/>\n          20.000<br \/>\n          10.000\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">10.000 <br \/>\n          10.000 <br \/>\n          10.000 \n      <\/div>\n<\/td>\n<td>\n<div align=\"right\">3.000.000<br \/>\n          2.000.000<br \/>\n          1.000.000\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">10.000.000<br \/>\n          10.000.000<br \/>\n          10.000.000\n       <\/div>\n<\/td>\n<td>\n<div align=\"right\">200.000<br \/>\n        200.000<br \/>\n      200.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">13.200<br \/>\n          12.200<br \/>\n          11.200\n       <\/div>\n<\/td>\n<td>\n<div align=\"right\">13.213.200<br \/>\n          12.212.200<br \/>\n          11.211.200\n    <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;    <\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad en el origen al tanto i<sub>m<\/sub> = 12%<\/p>\n<p>1.\u00aa posibilidad: aplicando las definiciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p549-02.png\" width=\"467\" height=\"71\" \/><\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p550-01.png\" width=\"469\" height=\"187\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>2.\u00aa posibilidad: aplicando el sistema de ecuaciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p550-02.png\" width=\"265\" height=\"111\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando las definiciones calculamos nuda propiedad y complemento:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p550-03.png\" width=\"317\" height=\"132\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Del sistema se despeja el usufructo y a continuaci\u00f3n el valor:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p550-04.png\" width=\"348\" height=\"38\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h4>  9.3.2.5. Cup\u00f3n fraccionado<\/h4>\n<p> Afecta al usufructo e, indirectamente, al valor, pero no a la nuda propiedad.<\/p>\n<p> El sistema de ecuaciones sigue siendo v\u00e1lido pero recogiendo el efecto del fraccionamiento en el usufructo y en el valor del t\u00edtulo.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p551-01.png\" width=\"254\" height=\"122\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Al tratarse de un empr\u00e9stito de cup\u00f3n fraccionado, para resolverlo, <em>obligatoriamente<\/em>, se tendr\u00e1 que calcular en primer lugar, y fuera del sistema, la nuda propiedad (N<sub>t<\/sub>) aplicando la definici\u00f3n, esto es, actualizando los valores de reembolso futuros al tanto de mercado.<\/p>\n<p>Del sistema se despejar\u00e1 siempre el usufructo y el valor.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 30 <\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 10.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n semestral: 60 euros.<\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Sorteos anuales a la par.<\/li>\n<li> Anualidad comercial constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li>  Cuadro de amortizaci\u00f3n.<\/li>\n<li> Valor, usufructo y nuda propiedad a principios del a\u00f1o 2 a un tanto de mercado del 15% efectivo anual.<\/li>\n<\/ul>\n<p class=\"progress\"> Soluci\u00f3n:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p552-01.png\" width=\"476\" height=\"214\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p552-02.png\" width=\"425\" height=\"155\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp; <\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">A\u00f1o\/Sem.<\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulos vivos <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulo amortiz. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Total t\u00edt. amort. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Intereses <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Amortizaci\u00f3n <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00e9rmino amortizativo<\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1.1.<br \/>\n    1.2.<br \/>\n    2.1.<br \/>\n    2.2.<br \/>\n    3.1.<br \/>\n    3.2.<\/div>\n<\/td>\n<td>\n<div align=\"right\">10.000<br \/>\n      10.000<br \/>\n      7.047<br \/>\n       7.047<br \/>\n      3.729<br \/> <br \/>\n      3.729<\/div>\n<\/td>\n<td>\n<div align=\"right\"> \u2013<br \/> <br \/>\n      2.953<br \/>\n      \u2013<br \/> <br \/>\n      3.318<br \/> <br \/>\n      \u2013<br \/> <br \/>\n      3.729<\/div>\n<\/td>\n<td>\n<div align=\"right\"> \u2013<br \/>\n      2.953<br \/>\n      2.953<br \/> <br \/>\n      6.271<br \/> <br \/>\n      6.271<br \/> <br \/>\n      10.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">600.000<br \/> <br \/>\n      600.000<br \/> <br \/>\n      422.820<br \/> <br \/>\n      422.820<br \/>\n      223.740<br \/> <br \/>\n      223.740<\/div>\n<\/td>\n<td>\n<div align=\"right\"> \u2013<br \/> <br \/>\n      2.953.000<br \/>\n      \u2013<br \/> <br \/>\n      3.318.000<br \/> <br \/>\n      \u2013<br \/> <br \/>\n      3.729.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">600.000<br \/>\n      3.553.000<br \/>\n      422.820<br \/>\n      3.740.820<br \/> <br \/>\n      223.740<br \/> <br \/>\n      3.952.740    <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad transcurrido un a\u00f1o al tanto i<sub>m<\/sub> = 15%<\/p>\n<p>1.\u00aa posibilidad: aplicando las definiciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p553-01.png\" width=\"431\" height=\"193\" \/> <\/p>\n<p>&nbsp;<\/p>\n<p>2.\u00aa posibilidad: aplicando el sistema de ecuaciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p553-02.png\" width=\"484\" height=\"109\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando la expresi\u00f3n de c\u00e1lculo de la nuda propiedad:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p553-03.png\" width=\"369\" height=\"66\" \/><\/p>\n<p>&nbsp;<\/p>\n<p> Del sistema se despeja el usufructo y a continuaci\u00f3n el valor:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p553-04.png\" width=\"357\" height=\"52\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h3>  9.3.3. Empr\u00e9stitos clase II, tipo I, normal<\/h3>\n<p> Empr\u00e9stitos con t\u00e9rmino amortizativo constante y cup\u00f3n acumulado en r\u00e9gimen de compuesta pagadero a los t\u00edtulos que en cada sorteo resulten amortizados.<\/p>\n<p> La estructura del t\u00e9rmino amortizativo es la siguiente:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p554-01.png\" width=\"319\" height=\"65\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Se trata de realizar el c\u00e1lculo del valor, usufructo y nuda propiedad de un t\u00edtulo procedente de este empr\u00e9stito en un momento cualquiera considerando los posibles escenarios antes comentados.<\/p>\n<p class=\"progress\"> Caso 1: el t\u00edtulo resultar\u00e1 amortizado en el momento k+t <\/p>\n<p>Estamos suponiendo que se conoce con absoluta certeza el momento en que resultar\u00e1 amortizado el t\u00edtulo estudiado.<\/p>\n<p>Gr\u00e1ficamente el esquema de flujos pendientes desde la fecha de estudio (k) hasta el momento del sorteo (k+t): <\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p554-02.png\" width=\"520\" height=\"103\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Se calcular\u00e1 en primer lugar el valor y la nuda propiedad, aplicando la definici\u00f3n:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p554-03.png\" width=\"406\" height=\"61\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El usufructo resultar\u00e1 m\u00e1s pr\u00e1ctico obtenerlo por diferencias entre los dos datos previamente obtenidos: U<sub>k<\/sub> = V<sub>k<\/sub> \u2013 N<sub>k<\/sub>.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 31 <\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li> T\u00edtulos emitidos: 10.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n del 10% anual acumulable al momento del sorteo. <\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Anualidad comercial constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li>  Valor, usufructo y nuda propiedad en el origen de un t\u00edtulo que resultar\u00e1 amortizado en el primer sorteo, siendo el tanto de mercado el 9%.<\/li>\n<li> Valor, usufructo y nuda propiedad en el origen de un t\u00edtulo que resultar\u00e1 amortizado en el \u00faltimo sorteo, siendo el tanto de mercado el 9%.<\/li>\n<\/ul>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p> a) Si el t\u00edtulo se amortiza en el primer a\u00f1o:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p555-01.png\" width=\"404\" height=\"152\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>b) Si el t\u00edtulo se amortiza en el tercer a\u00f1o:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p555-02.png\" width=\"406\" height=\"155\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p class=\"progress\">  Caso 2: tomando como estimaci\u00f3n la vida media del empr\u00e9stito en la fecha de estudio<\/p>\n<p> Se desconoce el momento en que resultar\u00e1 amortizado el t\u00edtulo estudiado, por ello se toma como estimaci\u00f3n la vida media calculada para todo el empr\u00e9stito en la fecha donde se valora.<\/p>\n<p> Gr\u00e1ficamente el esquema de flujos pendientes desde la fecha de estudio (k) hasta el momento del sorteo (k + V<sub>m<\/sub>): <\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p556-01.png\" width=\"532\" height=\"102\" \/><\/p>\n<p>&nbsp;<\/p>\n<p> Se proceder\u00e1 de igual forma que en el caso anterior, pero tomando como horizonte temporal la vida media del empr\u00e9stito.<\/p>\n<p class=\"progress\">Caso 3: considerando valores medios<\/p>\n<p> En los dos casos anteriores, bien conociendo la fecha del sorteo bien tomando como horizonte de estudio la vida media del empr\u00e9stito, se considera \u00fanicamente el t\u00edtulo objeto de valoraci\u00f3n. Ahora, por el contrario, se trabaja con el conjunto de t\u00edtulos vivos en la fecha de estudio del empr\u00e9stito, para, despu\u00e9s, estimar el valor medio de cada uno de ellos.<\/p>\n<p> El esquema de flujos pendientes del empr\u00e9stito en su conjunto es el siguiente:<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p556-02.png\" width=\"521\" height=\"99\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aplicando las definiciones de usufructo, nuda propiedad y valor, en este caso aplicados para el conjunto del empr\u00e9stito (valores totales o globales):<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p557-01.png\" width=\"547\" height=\"250\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Estos valores globales se repartir\u00e1n entre el n\u00famero de t\u00edtulos vivos en la fecha de estudio (N<sub>k+1<\/sub>), para obtener los valores medios por t\u00edtulo de usufructo, nuda propiedad y valor:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p557-02.png\" width=\"506\" height=\"65\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>No obstante, este proceso de c\u00e1lculo exige conocer los t\u00edtulos amortizados en cada momento desde la fecha de estudio hasta el final del empr\u00e9stito y las cantidades a pagar a cada uno de ellos en concepto de amortizaci\u00f3n y cup\u00f3n acumulado. <\/p>\n<p>Un sistema alternativo ser\u00eda el siguiente: <\/p>\n<p> \u2022 En primer lugar se calcula el valor medio de un t\u00edtulo:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p557-03.png\" width=\"150\" height=\"60\" \/><\/p>\n<p>\u2022 A continuaci\u00f3n se calcula la nuda propiedad, con la siguiente expresi\u00f3n:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p557-04.png\" width=\"259\" height=\"60\" \/><\/p>\n<p> \u2022 Finalmente, se despeja el usufructo:<\/p>\n<p> U<sub>k<\/sub> = V<sub>k<\/sub> \u2013 N<sub>k<\/sub><\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 32<\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li>  T\u00edtulos emitidos: 10.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n del 10% anual acumulable al momento del sorteo. <\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Anualidad comercial constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li>  Cuadro de amortizaci\u00f3n.<\/li>\n<li> Valor, usufructo y nuda propiedad en el origen a un tanto de mercado del 12% efectivo anual.<\/li>\n<\/ul>\n<p class=\"progress\"> Soluci\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p558-01.png\" width=\"281\" height=\"298\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">A\u00f1o \n        <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulos vivos <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulo amortiz. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Total t\u00edt. amort. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Intereses <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Amortizaci\u00f3n <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00e9rmino amortizativo<\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1<br \/>\n        2<br \/>\n        3\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">10.000<br \/>\n        6.344<br \/>\n        3.021\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">3.656<br \/>\n        3.323<br \/>\n        3.021\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\">3.656<br \/>\n        6.979<br \/>\n        10.000\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 365.600<br \/>\n        697.830<br \/>\n        999.951\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 3.656.000<br \/>\n        3.323.000<br \/>\n        3.021.000\n    <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 4.021.600<br \/>\n        4.020.830<br \/>\n        4.020.951\n    <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad en el origen al tanto i<sub>m<\/sub> = 12%<\/p>\n<p>1.\u00aa posibilidad: aplicando las definiciones<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p559-01.png\" width=\"434\" height=\"178\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>2.\u00aa posibilidad: calculando el valor medio y a continuaci\u00f3n la nuda propiedad con las expresiones abreviadas<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p559-02.png\" width=\"343\" height=\"134\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente se despeja el usufructo:<\/p>\n<p> U<sub>0<\/sub> = V<sub>0<\/sub> \u2013 N<sub>0<\/sub> = <span class=\"progress\">159,45<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h3>  9.3.4. Valor, usufructo y nuda propiedad en una fracci\u00f3n de per\u00edodo<\/h3>\n<p> Las expresiones anteriores se pueden aplicar para valoraciones efectuadas en momentos donde tiene lugar amortizaci\u00f3n de t\u00edtulos (final de per\u00edodo \u2013a\u00f1o\u2013). Si el c\u00e1lculo se realizar\u00e1 en cualquier otro momento de tiempo las definiciones siguen siendo v\u00e1lidas (y, por tanto, se pueden seguir aplicando) pero el sistema pr\u00e1ctico de ecuaciones no se podr\u00eda aplicar directamente.<\/p>\n<p> En este caso con el sistema de ecuaciones se realizar\u00e1n los c\u00e1lculos a principios del per\u00edodo y despu\u00e9s capitalizaremos hasta la fecha en la que se piden los valores. <em>Esta capitalizaci\u00f3n se debe efectuar en r\u00e9gimen de compuesta y al tanto de mercado <\/em>(i<sub>m<\/sub>).<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p560-01.png\" width=\"499\" height=\"317\" \/><\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 33<\/strong><\/p>\n<p>Se emite el siguiente empr\u00e9stito:<\/p>\n<ul>\n<li> T\u00edtulos emitidos: 20.000.<\/li>\n<li> Nominal t\u00edtulo: 1.000 euros.<\/li>\n<li> Cup\u00f3n anual: 50 euros.<\/li>\n<li> Prima de amortizaci\u00f3n: 200 euros.<\/li>\n<li> Duraci\u00f3n: 4 a\u00f1os.<\/li>\n<li> Gastos de administraci\u00f3n del 1\u2030 de las cantidades pagadas a los obligacionistas.<\/li>\n<li> Anualidad comercial constante.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li> Cuadro de amortizaci\u00f3n.<\/li>\n<li> Valor, usufructo y nuda propiedad transcurridos dos a\u00f1os desde la emisi\u00f3n a un tanto de mercado del 7% efectivo anual<\/li>\n<li> Valor, usufructo y nuda propiedad transcurridos dos a\u00f1os y tres meses desde la emisi\u00f3n a un tanto de mercado del 7% efectivo anual.<\/li>\n<\/ul>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p>&nbsp; <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p561-01.png\" width=\"413\" height=\"370\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>de donde:<\/p>\n<p class=\"progress\"> a = 6.644.388,60 <\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p562-01.png\" width=\"414\" height=\"176\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"progress\"> Cuadro de amortizaci\u00f3n<\/p>\n<p>&nbsp; <\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">A\u00f1o \n          <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulos vivos <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00edtulo amortiz. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Total t\u00edt. amort. <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Intereses <\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">Amortiz.<\/div>\n<\/p><\/div>\n<\/td>\n<td>\n<div align=\"center\"><span class=\"progress\">Gastos Adm&oacute;n. <\/span><\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress progress\">\n<div align=\"center\">T\u00e9rmino amortizativo<\/div>\n<\/p><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1<br \/>\n        2<br \/>\n        3<br \/>\n        4\n      <\/div>\n<\/td>\n<td>\n<div align=\"right\">20.000<br \/>\n          15.302<br \/>\n          10.408<br \/>\n          5.310          \n      <\/div>\n<\/td>\n<td>\n<div align=\"right\">4.698<br \/> <br \/>\n      4.894<br \/> <br \/>\n      5.098<br \/> <br \/>\n      5.310<\/div>\n<\/td>\n<td>\n<div align=\"right\">4.698<br \/> <br \/>\n      9.592<br \/> <br \/>\n      14.698<br \/> <br \/>\n      20.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">1.000.000<br \/> <br \/>\n      765.100<br \/> <br \/>\n      520.400<br \/> <br \/>\n      265.500<\/div>\n<\/td>\n<td>\n<div align=\"right\">5.637.600<br \/> <br \/>\n      5.872.800<br \/> <br \/>\n      6.117.600<br \/> <br \/>\n      6.372.000<\/div>\n<\/td>\n<td>\n<div align=\"right\">6.637,6<br \/> <br \/>\n      6.637,9<br \/> <br \/>\n      6.638,0<br \/> <br \/>\n      6.637,5<\/div>\n<\/td>\n<td>\n<div align=\"right\">6.644.237,6<br \/> <br \/>\n      6.644.537,9<br \/> <br \/>\n      6.644.638,0<br \/> <br \/>\n      6.644.137,5  <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;  <\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad en 2, al tanto i<sub>m<\/sub> = 7 % (aplicando las definiciones)<\/p>\n<p>&nbsp;<\/p>\n<p align=\"left\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p562-02.png\" width=\"401\" height=\"203\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Los mismos resultados se habr\u00edan obtenido aplicando el sistema de ecuaciones.<\/p>\n<p class=\"progress\">Valor, usufructo y nuda propiedad transcurridos 2 a\u00f1os y 3 meses, al tanto i<sub>m<\/sub> = 7%, (aplicando las definiciones)<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p563-01.png\" width=\"419\" height=\"201\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En este caso, para valorar en una fracci\u00f3n de per\u00edodo, el sistema de ecuaciones no se puede aplicar directamente. Habr\u00e1 que valorar en el momento 2 (V<sub>2<\/sub>, U<sub>2<\/sub> y N<sub>2<\/sub>) y despu\u00e9s capitalizar 3 meses al tanto de mercado. As\u00ed, utilizando los resultados del punto anterior se realizar\u00e1n finalmente los siguientes c\u00e1lculos:<\/p>\n<p> V<sub>2,25<\/sub> = V<sub>2<\/sub> x 1,07<sup>0,25<\/sup> = 1.153,04 x 1,07<sup>0,25<\/sup> = <span class=\"progress\">1.172,74<\/span><br \/>\n      U<sub>2,25<\/sub> = U<sub>2<\/sub> x 1,07<sup>0,25<\/sup> = 69,01 x 1,07<sup>0,25<\/sup> = <span class=\"progress\">70,22<\/span><br \/>\n      N<sub>2,25<\/sub> = N<sub>2<\/sub> x 1,07<sup>0,25<\/sup> = 1.084,06 x 1,07<sup>0,25<\/sup> = <span class=\"progress\">1.102,53<\/span>\n    <\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td><span class=\"progress\">Nota:<\/span> las peque\u00f1as diferencias que surgen entre los diferentes m\u00e9todos se deben al error de aproximaci\u00f3n que se comete tanto en uno como en otro. <\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La valoraci\u00f3n de t\u00edtulos procedentes de un empr\u00e9stito cualquiera implica conocer las cuant\u00edas de los derechos econ\u00f3micos futuros que dicho t\u00edtulo conlleva y actualizarlos al momento de estudio a un tipo adecuado (tanto de mercado). Definiciones: Valor de un t\u00edtulo en el momento k (principios del per\u00edodo k+1), Vk, es el resultado de actualizar al&#8230;<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":5093,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2128","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo - Blog de ADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo - Blog de ADE\" \/>\n<meta property=\"og:description\" content=\"La valoraci\u00f3n de t\u00edtulos procedentes de un empr\u00e9stito cualquiera implica conocer las cuant\u00edas de los derechos econ\u00f3micos futuros que dicho t\u00edtulo conlleva y actualizarlos al momento de estudio a un tipo adecuado (tanto de mercado). Definiciones: Valor de un t\u00edtulo en el momento k (principios del per\u00edodo k+1), Vk, es el resultado de actualizar al...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-18T07:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-01.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/\",\"name\":\"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo - Blog de ADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p534-01.png\",\"datePublished\":\"2016-07-18T07:12:21+00:00\",\"dateModified\":\"2016-07-18T07:13:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p534-01.png\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p534-01.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-3-valor-usufructo-nuda-propiedad-titulo-html\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"width\":940,\"height\":106,\"caption\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo - Blog de ADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/","og_locale":"es_ES","og_type":"article","og_title":"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo - Blog de ADE","og_description":"La valoraci\u00f3n de t\u00edtulos procedentes de un empr\u00e9stito cualquiera implica conocer las cuant\u00edas de los derechos econ\u00f3micos futuros que dicho t\u00edtulo conlleva y actualizarlos al momento de estudio a un tipo adecuado (tanto de mercado). Definiciones: Valor de un t\u00edtulo en el momento k (principios del per\u00edodo k+1), Vk, es el resultado de actualizar al...","og_url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/","og_site_name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","article_modified_time":"2016-07-18T07:13:04+00:00","og_image":[{"url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-01.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/","name":"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo - Blog de ADE","isPartOf":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/#primaryimage"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-01.png","datePublished":"2016-07-18T07:12:21+00:00","dateModified":"2016-07-18T07:13:04+00:00","breadcrumb":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/#primaryimage","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-01.png","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p534-01.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-3-valor-usufructo-nuda-propiedad-titulo-html\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/"},{"@type":"ListItem","position":2,"name":"9.3. Valor, usufructo y nuda propiedad de un t\u00edtulo"}]},{"@type":"WebSite","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","description":"","publisher":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","width":940,"height":106,"caption":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/2128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/comments?post=2128"}],"version-history":[{"count":2,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/2128\/revisions"}],"predecessor-version":[{"id":2130,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/2128\/revisions\/2130"}],"wp:attachment":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/media?parent=2128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}