{"id":2075,"date":"2016-07-15T13:13:13","date_gmt":"2016-07-15T13:13:13","guid":{"rendered":"http:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?page_id=2075"},"modified":"2016-07-15T13:13:57","modified_gmt":"2016-07-15T13:13:57","slug":"6-4-otros-activos-renta-fija-html","status":"publish","type":"page","link":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/","title":{"rendered":"6.4. Otros activos de renta fija"},"content":{"rendered":"<p>Con la denominaci\u00f3n gen\u00e9rica de \u00abactivos de renta fija\u00bb se refiere a todos aquellos t\u00edtulos que confieren a su propietario la condici\u00f3n de prestamista (acreedor) del emisor de los mismos, con independencia de la forma en que se documenten.<\/p>\n<p>El inversor que adquiere estos activos se asegura los siguientes derechos econ\u00f3micos, derivados de la condici\u00f3n de prestamista:<\/p>\n<ul>\n<li> Percepci\u00f3n de una ganancia (renta), peri\u00f3dica o \u00fanica, mientras se es propietario del t\u00edtulo.<\/li>\n<li> Derecho a recuperar la inversi\u00f3n efectuada, por el mismo valor u otro diferente (normalmente superior).<\/li>\n<li> Ganancia adicional (o p\u00e9rdida) por la venta anticipada del valor.<\/li>\n<\/ul>\n<p> Hoy d\u00eda, dada las diferentes modalidades de activos con que nos podemos encontrar en el mercado, no se puede definir un t\u00edtulo de renta fija como aquel que le supone a su propietario una rentabilidad segura (fija). Lo que verdaderamente define a cualquier t\u00edtulo de renta fija son los siguientes aspectos:<\/p>\n<ol>\n<li> El propietario es un acreedor de la sociedad emisora.<\/li>\n<li> Representa una parte de la(s) deuda(s) contra\u00edda(s) por el emisor.<\/li>\n<li> Pueden ser emitidos por cualquier entidad p\u00fablica o privada.<\/li>\n<li> Posibilidad de ser amortizados anticipadamente. <\/li>\n<\/ol>\n<h3>6.4.1. Pagar\u00e9s de empresa<\/h3>\n<p>Un pagar\u00e9 de empresa se define como un documento en el que se recoge un compromiso de pago contra\u00eddo por la sociedad emisora, a favor del tenedor del mismo, a una fecha fija, que es la de su vencimiento. El objetivo es el de la captaci\u00f3n de recursos financieros a corto plazo, para el emisor, o como un producto de inversi\u00f3n (para el suscriptor).<\/p>\n<p>El origen de este producto financiero son los denominados \u00abCommercial Paper\u00bb americanos. En Espa\u00f1a, la existencia de pagar\u00e9s de empresa data de octubre de 1982.<\/p>\n<p> Los pagar\u00e9s de empresa no suelen contar con ning\u00fan tipo de garant\u00eda espec\u00edfica, cuentan con la garant\u00eda general de la sociedad emisora, lo que hace necesario la exigencia de un buen <em>rating<\/em> (calificaci\u00f3n crediticia del emisor).<\/p>\n<p>Sus principales caracter\u00edsticas son:<\/p>\n<ul>\n<li> Valor nominal. Variable. Lo fija la sociedad emisora, siendo pr\u00e1ctica habitual un nominal de 1.000 \u00f3 3.000 euros.<\/li>\n<li> Intereses. Se emiten al descuento, pag\u00e1ndose una cantidad inferior a su valor nominal. La diferencia entre el valor nominal por el que se amortizan y el precio de compra es el inter\u00e9s de la inversi\u00f3n.<\/li>\n<li> Precios. El precio efectivo de emisi\u00f3n de cada pagar\u00e9 ser\u00e1 el que resulte, en funci\u00f3n del tipo de inter\u00e9s que se aplique y del plazo de vencimiento, en cada caso, de acuerdo con las f\u00f3rmulas siguientes:\n<p>    \u2013 Para plazos de vencimiento iguales o inferiores a 365 d\u00edas:<\/p>\n<p> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;N<br \/>\n        E = &#8212;&#8212;&#8212;&#8212;&#8212;&#8212; <br \/>\n        &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;n<br \/>\n        &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1 + i x &#8212;&#8212;-<br \/>\n      &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;365<\/p>\n<\/li>\n<\/ul>\n<p> \u2013 Para plazos de vencimiento superiores a 365 d\u00edas:<\/p>\n<p> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;N<br \/>\n      E = &#8212;&#8212;&#8212;&#8212;&#8212;-<br \/>\n      &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(1 + i)<sup>t\/365<\/sup><\/p>\n<p>siendo:<\/p>\n<p> i: Tipo de inter\u00e9s nominal en tanto por uno.<br \/>\n      N: Importe nominal del pagar\u00e9.<br \/>\n      E: Importe efectivo del pagar\u00e9.<br \/>\n    t: N\u00famero de d\u00edas del per\u00edodo, hasta vencimiento.<\/p>\n<p>\u2022 Plazo. Los pagar\u00e9s son activos financieros a corto plazo cuyo plazo de vencimiento se suele situar entre siete d\u00edas (7 d\u00edas) y dieciocho meses (548 d\u00edas). <\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 20<\/strong><\/p>\n<p>Se compra en mercado secundario un pagar\u00e9 de empresa de 1.000 euros nominal de Telef\u00f3nica, realiz\u00e1ndose la operaci\u00f3n con un tipo de descuento del 14%. El pagar\u00e9 vence a 180 d\u00edas y los gastos ascienden al 1,5\u2030 del nominal.<\/p>\n<p class=\"progress\">Se pide:<\/p>\n<p> \u00bfCu\u00e1l ser\u00e1 la liquidaci\u00f3n efectuada y la rentabilidad obtenida?<\/p>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p> El precio del t\u00edtulo (sin gastos) ser\u00e1: <\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-01.png\" width=\"408\" height=\"221\" \/><\/p>\n<p>\n    El precio de compra (gastos incluidos) es:<\/p>\n<p>Precio del pagar\u00e9 = 930,96 + 1,5\u2030 x 1.000 = 932,46 \u20ac<\/p>\n<p>La rentabilidad obtenida en esta operaci\u00f3n ser\u00e1:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-02.png\" width=\"406\" height=\"259\" \/> <\/p>\n<p>&nbsp; <\/p>\n<\/div>\n<p>&nbsp; <\/p>\n<h3>6.4.2. Obligaciones simples<\/h3>\n<p> Son t\u00edtulos que confieren a su titular la condici\u00f3n de prestamista de la sociedad emisora percibiendo por ello una renta peri\u00f3dica (fija o variable) durante la vida del t\u00edtulo y a la devoluci\u00f3n del capital aportado (por el nominal o con prima de reembolso).<\/p>\n<h3>6.4.3. Obligaciones subordinadas<\/h3>\n<p> Desde el punto de vista financiero las obligaciones subordinadas son t\u00edtulos de renta fija, normalmente con cup\u00f3n fijo y reembolso por el nominal o con prima.<\/p>\n<p> El t\u00e9rmino de \u00absubordinada\u00bb se refiere a que en caso de extinci\u00f3n y posterior liquidaci\u00f3n de la sociedad emisora, los obligacionistas subordinados son los \u00faltimos en cobrar, si bien, tienen preferencia de cobro frente a los accionistas, es decir, son los \u00faltimos acreedores y s\u00f3lo se sit\u00faan por delante de los accionistas. En consecuencia, en el supuesto de aplicaci\u00f3n de las reglas de prelaci\u00f3n de cr\u00e9ditos establecidas en el C\u00f3digo de Comercio y en el C\u00f3digo Civil por incurrir la sociedad emisora en un procedimiento concursal o de quiebra, los derechos y cr\u00e9ditos de los tenedores de estos valores frente a la sociedad emisora se situar\u00e1n, salvo que la legislaci\u00f3n aplicable estableciese otra cosa, detr\u00e1s de todos los acreedores comunes y de la siguiente manera:<\/p>\n<ol>\n<li> Tras los derechos y cr\u00e9ditos de todos los acreedores comunes de la sociedad emisora.<\/li>\n<li> Tras los derechos y cr\u00e9ditos de aquellos acreedores subordinados cuyo cr\u00e9dito se derive de una escritura p\u00fablica anterior a la fecha de la presente emisi\u00f3n.<\/li>\n<li> Con prioridad sobre todos los derechos de los accionistas y acreedores de la sociedad emisora caracterizados como otros acreedores asimilados a la aportaci\u00f3n de capital.<\/li>\n<\/ol>\n<p>Por lo dem\u00e1s, pueden tener las mismas caracter\u00edsticas que el resto de t\u00edtulos de renta fija (cup\u00f3n fijo o variable, valor de reembolso por nominal o con prima, pueden ser convertibles, emitirse con <em>warrant<\/em>\u2026).<\/p>\n<p>En Espa\u00f1a la emisi\u00f3n de t\u00edtulos de deuda subordinada ha sido muy utilizada por las entidades de cr\u00e9dito como una forma de capitalizaci\u00f3n de sus recursos propios, ya que la autoridad monetaria permite incluirlos como fondos propios. El total de deuda subordinada no puede superar el 30% de los recursos propios del emisor.<\/p>\n<h3>6.4.4. Bonos y obligaciones indiciadas, referenciadas o indexadas<\/h3>\n<p> En los bonos y obligaciones m\u00e1s comunes el importe del cup\u00f3n peri\u00f3dico queda fijado de antemano para toda la vida del t\u00edtulo. De esta forma, el poseedor del t\u00edtulo conoce siempre el importe de los intereses que va a percibir.<br \/>\n  Por el contrario, en los bonos u obligaciones indiciados el importe de los cupones var\u00eda total o parcialmente en funci\u00f3n de un \u00edndice de referencia preestablecido de antemano, que origina que el rendimiento de estos t\u00edtulos tenga car\u00e1cter variable.<br \/>\nUn caso particular son los llamados \u00ab<em>bonos bolsa<\/em>\u00bb cuya rentabilidad depende de un porcentaje sobre la revalorizaci\u00f3n de un \u00edndice burs\u00e1til (por ejemplo el Ibex-35 en el caso espa\u00f1ol). De esta manera, el inversor percibe dos tipos de ingresos: uno fijo (el valor nominal del t\u00edtulo) y otro peri\u00f3dico en funci\u00f3n de la evoluci\u00f3n del \u00edndice. Incluso cabe la posibilidad de que se asegure un cup\u00f3n peri\u00f3dico y el valor de reembolso se establezca, en todo o en parte, en funci\u00f3n de la revalorizaci\u00f3n del \u00edndice tomado como referencia.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 21 <\/strong><\/p>\n<p>Caja Duero emite bonos bolsa con las siguientes caracter\u00edsticas:<\/p>\n<ul>\n<li> Fecha de emisi\u00f3n: 16 de abril de X0.<\/li>\n<li> Bonos simples de 1.000 euros cada uno.<\/li>\n<li> N\u00famero de bonos emitidos: 30.000.<\/li>\n<li> Emisi\u00f3n al 100% del valor nominal, libre de comisiones y gastos para el suscriptor.<\/li>\n<li> Tipo de inter\u00e9s: no tiene. Se trata de una emisi\u00f3n cup\u00f3n cero. <br \/> <br \/>\n    La rentabilidad de estos bonos viene dada por la prima de amortizaci\u00f3n. La prima ascender\u00e1 a un porcentaje fijo, a aplicar sobre el nominal, equivalente al 40% de la revalorizaci\u00f3n que haya experimentado el \u00edndice Ibex-35 entre la fecha de emisi\u00f3n y la fecha de amortizaci\u00f3n.<\/li>\n<li> Amortizaci\u00f3n: el reembolso se realizar\u00e1 a la par, libre de gastos y de comisiones para el tenedor, adem\u00e1s de la prima de amortizaci\u00f3n variable.<br \/>\n      La devoluci\u00f3n del principal de los bonos se realizar\u00e1 en un solo pago el d\u00eda 16 de octubre de X2, no existiendo posibilidad de amortizaci\u00f3n anticipada por parte del emisor ni del suscriptor.<\/li>\n<li> Valor del Ibex-35 el 16 de abril de X0: 11.000 puntos.<\/li>\n<li> Gastos de emisi\u00f3n de 36.000 euros.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ol class=\"lalpha\">\n<li>  Rentabilidad de un bono si el Ibex-35 alcanza los 13.000 puntos el d\u00eda del vencimiento.<\/li>\n<li> Rentabilidad de un bono si el Ibex-35 no supera los 11.000 puntos el d\u00eda del vencimiento.<\/li>\n<li> Tanto efectivo del emisor.<\/li>\n<\/ol>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p><em> a) Primer supuesto: se produce una revalorizaci\u00f3n del \u00edndice (el Ibex-35 el d\u00eda de amortizaci\u00f3n del bono, 16 de octubre de X2, se sit\u00faa en 13.000 puntos<\/em><\/p>\n<p> <img decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p699-01.png\" \/><\/p>\n<p>La evoluci\u00f3n positiva del 18,18% del \u00edndice supone los siguientes flujos:<\/p>\n<p>&nbsp; <\/p>\n<table border=\"0\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress\">Fechas<\/div>\n<\/td>\n<td>&nbsp;&nbsp;&nbsp;<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Flujos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">16-04-X0<\/div>\n<\/td>\n<td>\n<div align=\"left\">Adquisici\u00f3n (nominal)&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..<\/div>\n<\/td>\n<td>\n<div align=\"center\">1.000,00 \u20ac<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">06-10-X2<\/div>\n<\/td>\n<td>\n<div align=\"left\">Reembolso (nominal + prima) &#8230;&#8230; <\/div>\n<\/td>\n<td>\n<div align=\"center\">1.072,73 \u20ac <\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p align=\"center\">&nbsp;  <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p700-01.png\" width=\"368\" height=\"153\" \/><\/p>\n<p>Siendo la rentabilidad final del t\u00edtulo la siguiente:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p699-02.png\" width=\"336\" height=\"80\" \/><\/p>\n<p><em>b) Segundo supuesto: el \u00edndice no experimenta variaci\u00f3n alguna o experimenta una variaci\u00f3n negativa<\/em><\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p699-03.png\" width=\"478\" height=\"105\" \/><\/p>\n<p>Si consideramos que la prima es igual a 0 el nominal y el valor del reembolso coincidir\u00edan, siendo igual a 1.000 euros, con lo cual, la rentabilidad del t\u00edtulo es:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p699-04.png\" width=\"218\" height=\"77\" \/><\/p>\n<p><em>c) Inter\u00e9s efectivo previsto para el emisor<\/em><\/p>\n<p> Depende de la revalorizaci\u00f3n alcanzada por el \u00edndice Ibex-35 y de los gastos en que finalmente se incurra. Resultando diferentes tipos de inter\u00e9s efectivo, en funci\u00f3n del incremento porcentual que pueda tener el \u00edndice y, por tanto, la variaci\u00f3n que sufra el valor de la prima, ya que el nominal de la emisi\u00f3n y los costes fijos de la emisi\u00f3n son constantes. <\/p>\n<p>El c\u00e1lculo del coste efectivo para el emisor se efectuar\u00e1 de acuerdo con la siguiente f\u00f3rmula:<\/p>\n<p>R = (V \u2013 C) x (1 + i)<sup>n<br \/>\n  <\/sup><\/p>\n<p> siendo:<\/p>\n<p> R: Valor de reembolso (nominal emisi\u00f3n m\u00e1s primas).<br \/>\n      V: Nominal emisi\u00f3n.<br \/>\n      C: Gastos de la emisi\u00f3n.<br \/>\n      n: N\u00famero de d\u00edas de la inversi\u00f3n\/365.<br \/>\n      i<sub>e<\/sub>: Coste efectivo.<\/p>\n<p>De donde:<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p701-01.png\" width=\"186\" height=\"77\" \/><\/p>\n<p>Retomando el primer supuesto en el que se produce una revalorizaci\u00f3n del \u00edndice y trat\u00e1ndolo a la f\u00f3rmula anterior nos resultar\u00eda:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p701-02.png\" width=\"389\" height=\"98\" \/><\/p>\n<p>Si tomamos el segundo supuesto en el que la prima es igual a cero, el nominal y el valor de reembolso coincidir\u00edan, siendo igual a 1.000 euros, con lo cual:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p701-03.png\" width=\"370\" height=\"107\" \/><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h3>  6.4.5. Obligaciones bonificadas<\/h3>\n<p> Desde el punto de vista puramente financiero, no son m\u00e1s que un caso concreto de obligaciones simples, donde el cup\u00f3n suele ser peri\u00f3dico y fijo, siendo el valor de reembolso a la par (por el nominal). Se representan mediante anotaciones en cuenta y, una vez emitidas, cotizan en las bolsas de valores.<\/p>\n<p>Solamente pueden emitir esta clase de obligaciones las empresas concesionarias de autopistas y las el\u00e9ctricas, con autorizaci\u00f3n expresa por parte de la Direcci\u00f3n General de Tributos de la bonificaci\u00f3n fiscal. Dichos beneficios fiscales se conceden con car\u00e1cter provisional y condicionados a que a los fondos obtenidos por la sociedad emisora se les d\u00e9 la aplicaci\u00f3n prevista.<\/p>\n<p>El atractivo de estos t\u00edtulos radica en el hecho de que adem\u00e1s del cup\u00f3n tienen un tratamiento fiscal favorable que supone una importante reducci\u00f3n en los impuestos del obligacionista, con lo que finalmente consigue una alta rentabilidad financiero-fiscal.<\/p>\n<p>Los beneficios fiscales se deben a:<\/p>\n<ul>\n<li> Una bonificaci\u00f3n fiscal sobre las retenciones a cuenta de los Impuestos sobre la Renta de las Personas F\u00edsicas y sobre Sociedades, de forma que los intereses brutos son objeto de una retenci\u00f3n en la fuente del 1,20% (por lo que tambi\u00e9n se les conoce como <em>obligaciones de cup\u00f3n<\/em> 1,20).<\/li>\n<li> Deducci\u00f3n en cuota, como impuesto pagado a cuenta, hasta el 24%, siempre que por este motivo no resulte cuota negativa.<\/li>\n<\/ul>\n<p>Este doble tratamiento fiscal favorable origina que en igualdad de caracter\u00edsticas financieras sean preferibles estos t\u00edtulos frente a los no bonificados.<\/p>\n<p>Surge el concepto de <em>rentabilidad financiero-fiscal<\/em> para el inversor de obligaciones bonificadas, que se definen como el inter\u00e9s anual bruto que tendr\u00eda que ofrecer una inversi\u00f3n alternativa, sin ventajas fiscales, para que el inversor, seg\u00fan su tasa impositiva, despu\u00e9s de impuestos obtuviera el mismo rendimiento anual neto (TIR) que suscribiendo estas obligaciones bonificadas a la par y benefici\u00e1ndose de la bonificaci\u00f3n fiscal.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 22<\/strong><\/p>\n<p>Se emiten obligaciones bonificadas de AUPASA, cuyas caracter\u00edsticas y condiciones son:<\/p>\n<ul>\n<li>  Naturaleza: obligaciones con bonificaci\u00f3n fiscal sobre las retenciones a cuenta del IRPF.<\/li>\n<li> Nominal del t\u00edtulo: 5.000 euros.<\/li>\n<li> Fecha de emisi\u00f3n: 1 de enero de X1.<\/li>\n<li> Fecha de vencimiento: 31 de diciembre de X2.<\/li>\n<li> Precio de emisi\u00f3n: 100% del valor nominal.<\/li>\n<li> Cup\u00f3n: 12% anual.<\/li>\n<li> Pago de cup\u00f3n: 31 de diciembre.<\/li>\n<li> R\u00e9gimen fiscal: debido a la bonificaci\u00f3n, la retenci\u00f3n en la fuente ser\u00e1 del 1,20%, pudiendo realizar el suscriptor una deducci\u00f3n del 24% del cup\u00f3n bruto en su declaraci\u00f3n del IRPF.<br \/>\n      El pago de impuestos se realiza el 30 de junio del a\u00f1o siguiente.<\/li>\n<\/ul>\n<p class=\"progress\">Se pide:<\/p>\n<ul>\n<li> La corriente de cobros y pagos que genera la compra de un t\u00edtulo por un inversor cuyo tipo impositivo es del 30%.<\/li>\n<li> Rentabilidad efectiva de la operaci\u00f3n teniendo en cuenta los impuestos.<\/li>\n<li> Rentabilidad financiero-fiscal de estos t\u00edtulos bonificados.<\/li>\n<\/ul>\n<p class=\"progress\">Soluci\u00f3n:<\/p>\n<p class=\"progress\"> Esquema de cobros y pagos de la inversi\u00f3n<\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress\">Flujo (semestres) \n      <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Fecha <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(Suscripci\u00f3n) <br \/>\n  amortizaci\u00f3n <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Cup\u00f3n bruto<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Retenci\u00f3n (1,20%<br \/>\n  x Cup\u00f3n bruto)<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Pago  impuestos <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Flujos netos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">0<br \/>\n  1<br \/>\n  2<br \/>\n  3<br \/>\n  4<br \/>\n  5 <\/div>\n<\/td>\n<td>\n<div align=\"center\">01-01-X1<br \/>\n        30-06-X1<br \/>\n        31-12-X1<br \/>\n        30-06-X2<br \/>\n        31-12-X2<br \/>\n      30-06-X3 <\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 5.000<\/p>\n<p>          5.000 <\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\n        600<\/p>\n<p>        600<\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\n        \u2013 7,20<\/p>\n<p>      \u2013 7,20<\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\n<p>\n        \u2013 36<\/p>\n<p>        \u2013 36<\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 5.000<br \/>\n        \u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br \/>\n        592,80<br \/>\n        \u2013 36 <br \/>\n        5.592,80<br \/>\n      \u2013 36<\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"0\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"left\">Cup\u00f3n bruto (12% x 5.000) &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.\n      <\/div>\n<\/td>\n<td>\n<div align=\"right\">600<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"left\">Retenci\u00f3n (1,20% x 600) &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..\n      <\/div>\n<\/td>\n<td>\n<div align=\"right\">7,20<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"left\">Pago impuestos [(30% \u2013 24%) x 600] &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230; <\/div>\n<\/td>\n<td>\n<div align=\"right\">36<\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p class=\"progress\">Rentabilidad de la operaci\u00f3n (con impuestos)<\/p>\n<p> Ser\u00e1 el tanto de inter\u00e9s que resulte de enfrentar todos los pagos y los cobros que la operaci\u00f3n genera por todos los conceptos, considerando la cuant\u00eda de los flujos y el momento donde tenga lugar. Gr\u00e1ficamente:<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p704-01.png\" width=\"499\" height=\"137\" \/><\/p>\n<p align=\"center\">&nbsp;<\/p>\n<p>De la siguiente ecuaci\u00f3n se obtendr\u00e1 la rentabilidad neta de impuestos obtenida por este inversor con este t\u00edtulo.<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;592,80&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;36&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 5.592,80 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;36<br \/>\n      5.000 = &#8212;&#8212;&#8212;&#8212;&#8212; \u2013 &#8212;&#8212;&#8212;&#8212;&#8211; + &#8212;&#8212;&#8212;&#8212;&#8211; \u2013 &#8212;&#8212;&#8212;&#8212;&#8211; <br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(1 + i2)<sup>2<\/sup> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(1 + i2)<sup>3<\/sup>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (1 + i2)<sup>4<\/sup>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (1 + i2)<sup>5<\/sup> <\/p>\n<p> i<sub>2<\/sub> = 5,439%<\/p>\n<p>\n      i = (1 + i<sub>2<\/sub>)<sup>2<\/sup> \u2013 1 = 1,05439<sup>2<\/sup> \u2013 1 = 11,17%<\/p>\n<p> Rentabilidad financiero-fiscal de los t\u00edtulos bonificados<\/p>\n<p> La rentabilidad financiero-fiscal a la que se refiere este apartado no es una rentabilidad real obtenida por un inversor (esa rentabilidad real es la calculada en el punto anterior). Se trata de determinar el tipo de inter\u00e9s que tendr\u00eda que ofrecer un t\u00edtulo de igual nominal, duraci\u00f3n, frecuencia de pago de cupones \u2026 , pero sin bonificaci\u00f3n fiscal, es decir, con una fiscalidad propia de los t\u00edtulos de renta fija (retenci\u00f3n en la fuente del 15% sobre los cupones brutos y deducci\u00f3n de las retenciones efectivamente practicadas), para que al inversor le resultara indiferente comprar un t\u00edtulo bonificado u otro no bonificado (pero con el resto de caracter\u00edsticas id\u00e9nticas). A este tipo de cup\u00f3n es a lo que se conoce como rentabilidad financiero-fiscal de las bonificadas.<\/p>\n<p>Para el c\u00e1lculo de este tipo de inter\u00e9s (i) consideramos lo siguiente:<\/p>\n<ul>\n<li> Nominal t\u00edtulo: 5.000<\/li>\n<li> Cup\u00f3n bruto: 5.000 x i<\/li>\n<li> Retenci\u00f3n: 15% x 5.000 x i = 750 x i<\/li>\n<li> Pago impuestos: (30% \u2013 15%) x 5.000 x i = 750 x i<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<table border=\"1\" align=\"center\" cellpadding=\"5\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\" class=\"progress\">Flujo (semestres) \n      <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Fecha <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(Suscripci\u00f3n) <br \/>\n        amortizaci\u00f3n <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Cup\u00f3n bruto<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Retenci\u00f3n (1,20% x Cup\u00f3n bruto)<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Pago impuestos <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Flujos netos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">0<br \/>\n        1<br \/>\n        2<br \/>\n        3<br \/>\n        4<br \/>\n        5 <\/div>\n<\/td>\n<td>\n<div align=\"center\">01-01-X1<br \/>\n        30-06-X1<br \/>\n        31-12-X1<br \/>\n        30-06-X2<br \/>\n        31-12-X2<br \/>\n        30-06-X3 <\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 5.000<\/p>\n<p>        5.000 <\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\n        5.000 x i<\/p>\n<p>        5.000 x i<\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\n        \u2013 750 x i<\/p>\n<p>        \u2013 750 x i <\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\n<p>\n        \u2013 750 x i<\/p>\n<p>         \u2013 750 x i<\/p><\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 5.000<br \/>\n        \u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br \/>\n        4.250 x i<br \/>\n        \u2013 750 x i<br \/>\n        5.000 + 4.250 x i<br \/>\n         \u2013 750 x i<\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Gr\u00e1ficamente:<\/p>\n<p>&nbsp; <\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p705-01.png\" width=\"491\" height=\"147\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>En esta inversi\u00f3n se obliga a que los pagos y cobros financieramente sean equivalentes al tanto i2 = 5,439%, con lo que estamos obligando a que la rentabilidad de este t\u00edtulo coincida con la rentabilidad despu\u00e9s de impuestos que generaba el t\u00edtulo bonificado. El tipo de inter\u00e9s del cup\u00f3n (i) que haga posible la igualdad ser\u00e1 el tipo de inter\u00e9s anual que deber\u00e1 ofrecer un bono no bonificado para que al inversor le resulte indiferente uno u otro.<\/p>\n<p>&nbsp; <\/p>\n<p align=\"left\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;4.250 x i&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;750 x i&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;5.000 + 4.250 x i&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;750 x i<br \/>\n    5.000 = &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211; \u2013 &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;- + &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; \u2013 &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; <br \/>\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(1 + 0,05439)<sup>2<\/sup> &nbsp;&nbsp;&nbsp;&nbsp;(1 + 0,05439)<sup>3<\/sup>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(1 + 0,05439)<sup>4<\/sup>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (1 + 0,05439)<sup>5<\/sup> <\/p>\n<p align=\"center\">&nbsp;<\/p>\n<p align=\"center\">    i = 15,788%<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h3> 6.4.6. Obligaciones convertibles y canjeables<\/h3>\n<p> La convertibilidad (canjeabilidad) supone la posibilidad de transformar un activo financiero en otro diferente mediante la aplicaci\u00f3n de determinadas reglas.<\/p>\n<p>En el caso de las obligaciones convertibles, el poseedor de estos t\u00edtulos tiene la posibilidad de que, llegado el momento acordado y en las condiciones pactadas, pueda cambiar el t\u00edtulo de renta fija por un determinado n\u00famero de acciones emitidas por la empresa (acciones nuevas). En otras ocasiones, la conversi\u00f3n se inicia unilateralmente por parte del emisor.<\/p>\n<p>Hasta la fecha de la conversi\u00f3n, el tenedor del t\u00edtulo (obligacionista) obtiene los derechos que le confiere el ser acreedor de la sociedad: el cobro de un cup\u00f3n peri\u00f3dico o, en su caso, la cuant\u00eda obtenida por la venta si enajena el valor antes de la conversi\u00f3n.<\/p>\n<p>Una vez llegado el momento de la conversi\u00f3n, puede optar por dos alternativas:<\/p>\n<ul>\n<li>  Si considera que el precio de las acciones a recibir es superior al que el inversor estima como valor objetivo, ejercitar\u00e1 la conversi\u00f3n y se convertir\u00e1 en accionista de la sociedad.<\/li>\n<li> Si considera que el precio de las acciones a recibir es inferior al que el inversor estima como valor objetivo, no ejercitar\u00e1 la conversi\u00f3n y continuar\u00e1 siendo acreedor hasta el vencimiento del t\u00edtulo.<\/li>\n<\/ul>\n<p>Por \u00faltimo, una cuesti\u00f3n importante es saber la proporci\u00f3n de conversi\u00f3n y c\u00f3mo se valoran los t\u00edtulos entregados (obligaciones) y recibidos (acciones).<\/p>\n<p>En el caso de las obligaciones canjeables, todo es exactamente igual salvo que las acciones que se entregan no son nuevas (lo que ocurre en la conversi\u00f3n) sino que se trata de acciones antiguas ya en circulaci\u00f3n.<\/p>\n<h3>6.4.7. Bonos y obligaciones con <em>warrant<\/em><\/h3>\n<p> Un <em>warrant<\/em> es un certificado de opci\u00f3n mediante el cual el tenedor de una obligaci\u00f3n tiene la posibilidad de adquirir en un momento futuro y a un precio determinado de antemano un n\u00famero concreto de acciones de la misma empresa que emiti\u00f3 las obligaciones. De esta forma, el inversor encuentra un mayor atractivo en la suscripci\u00f3n de las obligaciones y a la empresa emisora de las obligaciones le resulta m\u00e1s f\u00e1cil su colocaci\u00f3n.<\/p>\n<p>El <em>warrant<\/em> se negocia por separado del activo al cual aparece ligado. Su titular puede venderlo en cualquier momento o ejercitarlo en el momento que corresponda. En este sentido, el propietario de un <em>warrant<\/em> esperar\u00e1 a que el activo de renta fija suba de precio por encima del pactado en el <em>warrant<\/em> para as\u00ed ejercitar el derecho de compra a un precio inferior al de mercado. En caso contrario, puede optar por desprenderse del <em>warrant<\/em>. Es decir, llegado el vencimiento del <em>warrant<\/em> el obligacionista comprar\u00e1 la acci\u00f3n a la que da derecho cuando su precio sea inferior al de mercado, y no lo har\u00e1 en caso contrario.<\/p>\n<p>La diferencia entre las obligaciones con <em>warrant<\/em> y las obligaciones convertibles es que en las primeras la utilizaci\u00f3n de la opci\u00f3n de suscripci\u00f3n de acciones que incorpora el <em>warrant<\/em> no requiere, necesariamente, la desaparici\u00f3n o amortizaci\u00f3n de las obligaciones. En otras palabras, el titular que hasta ese momento era s\u00f3lo obligacionista sigue si\u00e9ndolo y, adem\u00e1s, se convierte en accionista. En todo caso, tambi\u00e9n puede darse el caso de una obligaci\u00f3n convertible con <em>warrant<\/em>.<\/p>\n<h3>6.4.8. T\u00edtulos hipotecarios<\/h3>\n<p> Se distinguen tres categor\u00edas de t\u00edtulos que permiten a sus emisores captar fondos a medio y largo plazo con el \u00fanico objetivo de invertir estos recursos en operaciones con garant\u00eda hipotecaria:<\/p>\n<ul>\n<li> C\u00e9dulas hipotecarias.<\/li>\n<li> Bonos hipotecarios.<\/li>\n<li> Participaciones hipotecarias.<\/li>\n<\/ul>\n<p>Por tanto, hay que distinguir las operaciones pasivas de los emisores que les permiten captar fondos y, por otro, las operaciones activas de pr\u00e9stamos con garant\u00eda hipotecaria a los que deben ir dirigidos gran parte de estos fondos.<\/p>\n<p>Las <em>c\u00e9dulas hipotecarias<\/em> son t\u00edtulos garantizados por todos los cr\u00e9ditos hipotecarios concedidos por el emisor. Por tanto, sus tenedores son acreedores privilegiados del emisor, teniendo garantizados tanto el capital como los intereses, gracias a las hipotecas inscritas a favor de ellos mismos.<\/p>\n<p>La diferencia entre c\u00e9dulas y <em>bonos hipotecarios<\/em> radica en su garant\u00eda. En estos \u00faltimos, existe la seguridad de un cr\u00e9dito, o grupo de cr\u00e9ditos, en concreto. Cada emisi\u00f3n tiene que quedar vinculada, mediante una escritura p\u00fablica, a los cr\u00e9ditos hipotecarios que la garantizan, por lo que su vencimiento medio casi siempre oscila entre uno y tres a\u00f1os, y sus intereses no pueden superar a los de dichos cr\u00e9ditos.<\/p>\n<p>Las <em>participaciones hipotecarias<\/em> representan la cesi\u00f3n total o parcial de un pr\u00e9stamo hipotecario de una entidad a otra o al p\u00fablico (aunque es m\u00e1s habitual entre entidades), de manera que \u00abparticipa\u00bb en el pr\u00e9stamo hipotecario y cobra la parte de los intereses del pr\u00e9stamo que le corresponden de acuerdo con su participaci\u00f3n relativa. Habitualmente incorporan un porcentaje sobre el principal de uno o varios cr\u00e9ditos de la entidad emisora, y s\u00f3lo pueden ser emitidas por la entidades autorizadas para operar en el mercado hipotecario. En resumen, las participaciones se configuran como una cesi\u00f3n de cr\u00e9dito.<\/p>\n<p>En otras palabras, las participaciones hipotecarias permiten participar a los inversores de los cr\u00e9ditos hipotecarios que conceden las entidades que act\u00faan en el mercado hipotecario, conservando \u00e9stas la administraci\u00f3n y la custodia de los cr\u00e9ditos.<\/p>\n<p>Las participaciones hipotecarias se emiten casi siempre a largo plazo, al contrario que las c\u00e9dulas y bonos hipotecarios, que generalmente son a corto o medio plazo.<\/p>\n<p>Es importante subrayar que a diferencia de lo que ocurre con los bonos y las c\u00e9dulas hipotecarias, el inversor o part\u00edcipe no percibe un ingreso procedente de los intereses o cupones prefijados por el emisor, sino que percibe directamente la parte proporcional del pr\u00e9stamo hipotecario, lo cual tiene como consecuencia que, en caso de impago del pr\u00e9stamo hipotecario, el adquirente de estas participaciones asuma el riesgo de impago por parte del prestatario.<\/p>\n<h3>6.4.9. Bonos y obligaciones de titulizaci\u00f3n hipotecaria<\/h3>\n<p> Son un tipo de bonos que empieza a tener una presencia cada vez m\u00e1s importante ya que permite a las entidades financieras desmovilizar su cartera de cr\u00e9ditos.<\/p>\n<p>Este tipo de bonos es emitido por los denominados Fondos de Titulizaci\u00f3n Hipotecaria, constituidos al efecto y, generalmente, por entidades financieras que tienen en su cartera diversos pr\u00e9stamos hipotecarios. De esta manera, lo que hace el fondo hipotecario es transformar las c\u00e9dulas, bonos y participaciones hipotecarias en otros t\u00edtulos (los bonos de titulizaci\u00f3n hipotecaria) que se negocian como un activo nuevo en el mercado.<\/p>\n<p>Los Fondos de Titulizaci\u00f3n Hipotecaria son agrupaciones hipotecarias que transforman el conjunto de los pr\u00e9stamos o participaciones hipotecarias que adquieran de entidades de cr\u00e9dito, en valores de renta fija negociables en un mercado de valores organizados. La constituci\u00f3n y administraci\u00f3n de estos fondos corresponde a las Sociedades Gestoras de Fondos de Titulizaci\u00f3n Hipotecaria.<\/p>\n<p>En cuanto a la operativa financiera de los bonos de titulizaci\u00f3n hipotecaria, reciben igual tratamiento que el resto de los bonos ya que abonan intereses o cupones peri\u00f3dicos y, generalmente, se amortizan por su valor nominal. A este respecto, el abono peri\u00f3dico de intereses a los part\u00edcipes de estos fondos hace que puedan calificarse como fondos de reparto.<\/p>\n<h3>6.4.10. Bonos de alto rendimiento, \u00abbonos basura\u00bb o <em>junk bond<\/em><\/h3>\n<p> Bajo esta denominaci\u00f3n se engloba a un conjunto de activos de renta fija cuya particularidad radica en el hecho de que los emisores suelen ser de escasa calidad crediticia y poca solvencia, por lo cual reparten altos rendimientos.<\/p>\n<p>El riesgo de estos t\u00edtulos es alto ya que la probabilidad de impago es elevada y, por consiguiente, se utilizan fundamentalmente con fines especulativos y sus emisores suelen ser empresas que necesitan financiaci\u00f3n a toda costa.<\/p>\n<p>En cuanto al resto de caracter\u00edsticas financieras, suelen ser t\u00edtulos de cup\u00f3n fijo peri\u00f3dico y amortizables a la par.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la denominaci\u00f3n gen\u00e9rica de \u00abactivos de renta fija\u00bb se refiere a todos aquellos t\u00edtulos que confieren a su propietario la condici\u00f3n de prestamista (acreedor) del emisor de los mismos, con independencia de la forma en que se documenten. El inversor que adquiere estos activos se asegura los siguientes derechos econ\u00f3micos, derivados de la condici\u00f3n&#8230;<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":6064,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2075","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6.4. Otros activos de renta fija - Blog de ADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6.4. Otros activos de renta fija - Blog de ADE\" \/>\n<meta property=\"og:description\" content=\"Con la denominaci\u00f3n gen\u00e9rica de \u00abactivos de renta fija\u00bb se refiere a todos aquellos t\u00edtulos que confieren a su propietario la condici\u00f3n de prestamista (acreedor) del emisor de los mismos, con independencia de la forma en que se documenten. El inversor que adquiere estos activos se asegura los siguientes derechos econ\u00f3micos, derivados de la condici\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-15T13:13:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-01.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/\",\"name\":\"6.4. Otros activos de renta fija - Blog de ADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p696-01.png\",\"datePublished\":\"2016-07-15T13:13:13+00:00\",\"dateModified\":\"2016-07-15T13:13:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p696-01.png\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p696-01.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/6-4-otros-activos-renta-fija-html\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6.4. Otros activos de renta fija\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"width\":940,\"height\":106,\"caption\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6.4. Otros activos de renta fija - Blog de ADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/","og_locale":"es_ES","og_type":"article","og_title":"6.4. Otros activos de renta fija - Blog de ADE","og_description":"Con la denominaci\u00f3n gen\u00e9rica de \u00abactivos de renta fija\u00bb se refiere a todos aquellos t\u00edtulos que confieren a su propietario la condici\u00f3n de prestamista (acreedor) del emisor de los mismos, con independencia de la forma en que se documenten. El inversor que adquiere estos activos se asegura los siguientes derechos econ\u00f3micos, derivados de la condici\u00f3n...","og_url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/","og_site_name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","article_modified_time":"2016-07-15T13:13:57+00:00","og_image":[{"url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-01.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/","name":"6.4. Otros activos de renta fija - Blog de ADE","isPartOf":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/#primaryimage"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-01.png","datePublished":"2016-07-15T13:13:13+00:00","dateModified":"2016-07-15T13:13:57+00:00","breadcrumb":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/#primaryimage","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-01.png","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p696-01.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/6-4-otros-activos-renta-fija-html\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/"},{"@type":"ListItem","position":2,"name":"6.4. Otros activos de renta fija"}]},{"@type":"WebSite","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","description":"","publisher":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","width":940,"height":106,"caption":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/2075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/comments?post=2075"}],"version-history":[{"count":2,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/2075\/revisions"}],"predecessor-version":[{"id":2077,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/2075\/revisions\/2077"}],"wp:attachment":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/media?parent=2075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}