{"id":207,"date":"2010-12-29T09:05:38","date_gmt":"2010-12-29T09:05:38","guid":{"rendered":"http:\/\/www.adeudima.com\/?page_id=207"},"modified":"2010-12-29T09:05:38","modified_gmt":"2010-12-29T09:05:38","slug":"5-modelos-basicos-de-organizacion","status":"publish","type":"page","link":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/","title":{"rendered":"5. Modelos b\u00e1sicos de organizaci\u00f3n"},"content":{"rendered":"<p>La combinaci\u00f3n de los principios antes expuestos y  el mayor o menor  \u00e9nfasis de los mismos permitir\u00e1n dise\u00f1ar unos modelos o formas   espec\u00edficas de la estructura de organizaci\u00f3n.<\/p>\n<p>Un resumen de las formas principales se recoge en la  tabla 4,  abordando los modelos simples y complejos cl\u00e1sicos, as\u00ed como, algunos   modelos nuevos de la organizaci\u00f3n.<\/p>\n<p><span style=\"text-decoration: underline;\">TABLA 4. LAS FORMAS ORGANIZATIVAS PRINCIPALES<\/span><\/p>\n<table style=\"height: 204px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"5\" width=\"742\" align=\"center\">\n<tbody>\n<tr>\n<td valign=\"top\">Formas    simples<\/td>\n<td>\u2022\u00a0\u00a0 Modelo lineal.<br \/>\n\u2022\u00a0\u00a0 Modelo funcional.<br \/>\n\u2022\u00a0\u00a0 Modelo adhocr\u00e1tico.<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Formas complejas cl\u00e1sicas<\/td>\n<td>\u2022\u00a0\u00a0 Modelo lineal-funcional.<br \/>\n\u2022\u00a0\u00a0 Modelo divisional.<br \/>\n\u2022\u00a0\u00a0 Modelo matricial.<br \/>\n\u2022\u00a0\u00a0 Modelo colegial.<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">Formas complejas nuevas<\/td>\n<td>\u2022\u00a0\u00a0 Modelo federal.<br \/>\n\u2022\u00a0\u00a0 Modelo en tr\u00e9bol.<br \/>\n\u2022\u00a0\u00a0 Modelo en red.<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\">\n<div><strong>Fuente: <\/strong><em>Bueno<\/em> (<em>2007<\/em>)<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>En primer lugar, se presentar\u00e1n las llamadas <strong>formas  simples<\/strong>, es decir, aquellas que se dise\u00f1an de acuerdo con la presencia  b\u00e1sica de uno de los tres modos de estructuraci\u00f3n.<\/p>\n<ul>\n<li>Modelo  lineal\u00a0 \u2192\u00a0  Principios b\u00e1sicos de dise\u00f1o vertical: jerarqu\u00eda.<\/li>\n<li>Modelo  funcional\u00a0 \u2192\u00a0 Principios b\u00e1sicos de dise\u00f1o horizontal:  especializaci\u00f3n.<\/li>\n<li>Modelo  adhocr\u00e1tico\u00a0 \u2192\u00a0 Principios b\u00e1sicos de dise\u00f1o del equilibrio:  motivaci\u00f3n.<\/li>\n<\/ul>\n<p>En segundo lugar se comentar\u00e1n  las <strong>formas complejas<\/strong> cl\u00e1sicas, es decir, aquellas que combinan de una  forma m\u00e1s o menos  compleja los distintos principios que estructuran en uno u  otro modo la  organizaci\u00f3n.<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" width=\"90%\">\n<tbody>\n<tr>\n<td valign=\"top\">Antes de entrar a exponer cada modelo hay que aclarar  que casi todas estas formas suelen ser dise\u00f1os burocr\u00e1ticos. La <strong>burocracia <\/strong>representa   una forma de estructurar jer\u00e1rquicamente la organizaci\u00f3n, partiendo de  la  unidad de mando y de la importancia de la estandarizaci\u00f3n,  formalizaci\u00f3n y  centralizaci\u00f3n de los procesos o flujos de trabajo  b\u00e1sicos de la empresa.  Frente a la burocracia, como forma estructural  externa, aparece la <strong>adhocracia <\/strong>como base de las  \u00abestructuras org\u00e1nicas\u00bb, es decir, apoyadas en procesos no   estandarizados, m\u00e1s flexibles y orientadas a una adaptaci\u00f3n  interpersonal y a  una comunicaci\u00f3n elevada entre las personas, lo que  generar\u00e1 un mayor n\u00famero de  relaciones informales. En la figura 8, se  comparan las tres caracter\u00edsticas  estructurales que diferencian ambos  enfoques: jerarquizaci\u00f3n, formalizaci\u00f3n  (normalizaci\u00f3n) y  centralizaci\u00f3n.<\/td>\n<td>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td width=\"377\">\n<div>\n<p>Figura 8. Burocracia y adhocracia:<br \/>\nenfoques del sistema estructural<\/p>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div><a href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-205\" title=\"02_05_01\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg\" alt=\"\" width=\"252\" height=\"244\" \/><\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>5.1.\u00a0 EL MODELO LINEAL<\/h2>\n<p>Este modelo se basa en el principio de la jerarqu\u00eda  y en el  mantenimiento de la unidad de mando. Con ello se refuerza el principio   de autoridad y la estructura se orienta burocr\u00e1ticamente hacia el  proceso o al  desarrollo piramidal (organizaci\u00f3n alta) de la misma, para  el caso de empresas  de cierto tama\u00f1o. Es una forma aconsejable para  empresas peque\u00f1as y medianas  con explotaciones simples o con un sistema  t\u00e9cnico poco sofisticado t\u00e9cnicamente,  dada su eficacia en la  supervisi\u00f3n de las tareas y el control de los  resultados, aparte de ser  una estructura de bajo coste de funcionamiento. En la  figura 9, se  recoge un ejemplo de este tipo de estructura u organigrama.<\/p>\n<p>Los mayores inconvenientes radican en la excesiva  concentraci\u00f3n de  autoridad, en la tendencia a la rigidez y en una cierta falta  de  respuesta t\u00e9cnica en entornos din\u00e1micos y competitivos.<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div>Figura 9. Modelo lineal de organizaci\u00f3n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div><a href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-206\" title=\"02_05_02\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_02.jpg\" alt=\"\" width=\"531\" height=\"336\" srcset=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_02.jpg 531w, https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_02-300x190.jpg 300w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>5.2.\u00a0 EL MODELO FUNCIONAL<\/h2>\n<p>Este modelo se apoya en la m\u00e1xima utilizaci\u00f3n de los  especialistas  funcionales en los niveles jer\u00e1rquicos principales. El objetivo  es  incrementar la productividad de la empresa gracias a la especializaci\u00f3n,  por  lo que a los puestos jer\u00e1rquicos se les despoja de cierta  autoridad y  responsabilidad en favor de dichos especialistas. Por lo  tanto, la estructura  se aplana o se desarrolla en su base operativa.<\/p>\n<p>Esta estructura fue propuesta por Taylor y se  caracteriza por  eliminar el principio de la unidad de mando, ya que el  trabajador  depender\u00e1 en la realizaci\u00f3n de sus tareas de cada uno de los   especialistas en cada fase productiva o funci\u00f3n empresarial.<\/p>\n<p>El mayor inconveniente se produce, precisamente, por  la ruptura de  la unidad de mando, lo que suele ser fuente de conflictos de  intereses y  objetivos y genera dificultades de coordinaci\u00f3n. En la figura 10,  se  representa un organigrama de este modelo.<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div>Figura 10. Modelo funcional de organizaci\u00f3n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div><a href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-208\" title=\"02_05_03\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_03.jpg\" alt=\"\" width=\"533\" height=\"341\" srcset=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_03.jpg 533w, https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_03-300x192.jpg 300w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>5.3.\u00a0 EL MODELO ADHOCR\u00c1TICO<\/h2>\n<p>Este modelo organizativo no tiene una estructura  definida, ya que  su dise\u00f1o puede adoptar diferentes formas, seg\u00fan cuales sean  las  necesidades de respuesta a las tareas y objetivos a desarrollar.<\/p>\n<p>Este modelo es dif\u00edcil de representar con un  organigrama  espec\u00edfico. Se basa en la aplicaci\u00f3n de los principios del  equilibrio  interno, siendo adem\u00e1s importante su gesti\u00f3n orientada a los  objetivos y  el \u00e9nfasis en el trabajo en equipo, gracias a la motivaci\u00f3n,   participaci\u00f3n y comunicaci\u00f3n entre sus miembros.<\/p>\n<p>Este tipo de organizaci\u00f3n es la consecuencia de unas  actitudes  positivas para el trabajo en grupo y unas aptitudes profesionales   destacadas y muy cualificadas, lo cual hace que sea caracter\u00edstica en  empresas  peque\u00f1as y medianas con un sistema t\u00e9cnico muy sofisticado o  intensivo en  tecnolog\u00edas avanzadas y con procesos productivos por  pedido y flexibles. Este  modelo es el usual en empresas de ingenier\u00eda o  de consultor\u00eda, o en centros de  estudio de I+D, descentralizados, de  empresas de mayor dimensi\u00f3n.<\/p>\n<h2>5.4.\u00a0 EL MODELO LINEO-FUNCIONAL<\/h2>\n<p>Este modelo es de naturaleza mixta, ya que combina  los principios  b\u00e1sicos del dise\u00f1o vertical y horizontal, con el fin de  aprovechar las  ventajas de los dos primeros modelos: lineal y funcional. De  otra  parte, tambi\u00e9n pretende evitar los inconvenientes de estas formas   organizativas.<\/p>\n<p>La parte central de la estructura se apoya en el  modelo jer\u00e1rquico,  basado en las relaciones lineales que lo configuran. Siendo  estas las  que ejecutan, supervisan y controlan los flujos de trabajo con que se   lleva a cabo la actividad de la empresa.<\/p>\n<p>Pero, con el fin de apoyar t\u00e9cnicamente a la l\u00ednea,  se dise\u00f1a en torno a esta parte central una estructura de \u00ab<em>staffs<\/em> directivos\u00bb  y de \u00abasesoramiento\u00bb, con el fin de que se logre la  especializaci\u00f3n y el apoyo  log\u00edstico necesarios para mejorar la  eficiencia de la empresa.<\/p>\n<p>El mayor inconveniente de este modelo,  caracter\u00edstico en la gran  empresa de las \u00faltimas d\u00e9cadas, es su excesiva  burocratizaci\u00f3n y su  elevada jerarquizaci\u00f3n, lo que unido a la multiplicidad de  expertos  funcionales y asesores lo convierte en un esquema lento de respuesta y   caro por los elevados costes de administraci\u00f3n. En la figura 11, se  recoge un  ejemplo de organigrama resumido.<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div>Figura 11. Modelo lineo-funcional de organizaci\u00f3n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div><a href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-209\" title=\"02_05_04\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_04.jpg\" alt=\"\" width=\"530\" height=\"400\" srcset=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_04.jpg 530w, https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_04-300x226.jpg 300w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>5.5.\u00a0 EL MODELO DIVISIONAL<\/h2>\n<p>Con el fin de dar mayor rapidez a la toma de  decisiones y autonom\u00eda  a las actividades de las empresas de gran tama\u00f1o,  superando los  inconvenientes del modelo anterior, se dise\u00f1a la forma  divisional, la  cual se basa en la utilizaci\u00f3n del principio de la  divisionalizaci\u00f3n,  sobre el que pivotan los restantes principios de uno u otro  modo de  estructurar la organizaci\u00f3n.<\/p>\n<p>Es un modelo bastante complejo y propio de grandes  empresas con un  sistema t\u00e9cnico multiproducto y multimercado y en donde la  direcci\u00f3n y  el poder de sus miembros representan el aspecto dominante de su   funcionamiento. Tambi\u00e9n suele ser una estructura caracter\u00edstica de las  empresas  multinacionales. En el ep\u00edgrafe siguiente ser\u00e1n ampliadas  algunas de sus  caracter\u00edsticas.<\/p>\n<p>El problema fundamental reside en el establecimiento  de un criterio  para divisionalizar la empresa o para crear las unidades  aut\u00f3nomas de  actuaci\u00f3n, como si fueran \u00abcuasi-empresas\u00bb. Los criterios m\u00e1s   utilizados son los siguientes:<\/p>\n<ul>\n<li>Productos  o l\u00edneas de producto.<\/li>\n<li>Mercados, bien por \u00e1reas geogr\u00e1ficas o por tipos de clientes  (segmentos).<\/li>\n<li>Funciones empresariales y procesos productivos diferenciados.<\/li>\n<\/ul>\n<p>Lo normal es empezar a divisionalizar partiendo de  un criterio y  luego utilizar sucesivamente los otros para establecer nuevas   subdivisiones o \u00e1reas org\u00e1nicas. Las empresas industriales suelen  empezar por  productos, las empresas de servicios por segmentos de  mercados o tipos de  clientes y las empresas multinacionales lo suelen  hacer por \u00e1reas geogr\u00e1ficas  de su mercado internacional o global.<\/p>\n<p>Estas divisiones suelen tambi\u00e9n recibir el nombre de  \u00abunidad  estrat\u00e9gica de negocio\u00bb y se definen como centros de beneficios,   dotadas con sus recursos espec\u00edficos y la correspondiente fijaci\u00f3n de  objetivos,  raz\u00f3n por la que lo normal es que se act\u00fae con una direcci\u00f3n  por objetivos. En  la figura 12, se recoge un ejemplo resumido de  organigrama de una empresa  industrial.<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div>Figura 12. Modelo divisional de organizaci\u00f3n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div><a href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-210\" title=\"02_05_05\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_05.jpg\" alt=\"\" width=\"532\" height=\"517\" srcset=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_05.jpg 532w, https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_05-300x292.jpg 300w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>5.6.\u00a0 EL MODELO MATRICIAL<\/h2>\n<p>Hay autores que no consideran este modelo como una  aut\u00e9ntica  estructura organizativa, sino m\u00e1s bien como una forma m\u00e1s de  coordinar  las actividades y los objetivos de la organizaci\u00f3n.<\/p>\n<p>Si la estructura funcional ofrece las ventajas de la   especializaci\u00f3n y si la divisional se concentra en la obtenci\u00f3n de los  resultados  finales, se podr\u00eda intentar alguna combinaci\u00f3n de ambas para  as\u00ed lograr una  mejora de la eficiencia de la organizaci\u00f3n, sin caer en  los elevados costes de  la segunda al estructurarse jer\u00e1rquicamente en  diferentes niveles divisionales  y evitando el conflicto de objetivos de  la primera. Esta es la pretensi\u00f3n del  modelo matricial: crear dos o  tres dimensiones, seg\u00fan los criterios aplicados,  para estructurar la  direcci\u00f3n intermedia, bien por productos o proyectos, bien  por mercados  o clientes o bien, en su caso, por funciones o procesos.<\/p>\n<p>La estructura matricial establece dos o tres fuentes  de mando sobre  la \u00abbase de operaciones\u00bb, con el fin de responsabilizar a los   directivos de producto, proyecto, mercado o cliente de sus objetivos y   coordinar adecuadamente los distintos aspectos del flujo de trabajo.  Esto  significa que, al menos, todo empleado tiene dos o tres jefes: el  gerente  funcional, de car\u00e1cter jer\u00e1rquico, y el gerente de producto o  proyecto y,  posiblemente, el gerente de mercado o cliente, seg\u00fan que se  est\u00e9 contemplando  un modelo de dos o tres dimensiones. Un ejemplo  convencional de dos dimensiones  se recoge en la figura 13. Organigrama  que suele ser caracter\u00edstico en empresas  de cierta dimensi\u00f3n, con  sistema t\u00e9cnico complejo y con cierta diferenciaci\u00f3n  entre productos,  proyectos, mercados y clientes.<\/p>\n<p>El mayor inconveniente de esta estructura es la  confusi\u00f3n que se  puede producir si la direcci\u00f3n general no coordina y equilibra  bien el  peso y papel de cada una de las dimensiones directivas. Tambi\u00e9n es un   modelo propenso a la existencia de luchas de poder entre los directivos.<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"5\" align=\"center\">\n<tbody>\n<tr>\n<td>\n<div>Figura 13. Modelo matricial de organizaci\u00f3n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div><a href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_06.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-211\" title=\"02_05_06\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_06.jpg\" alt=\"\" width=\"535\" height=\"410\" srcset=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_06.jpg 535w, https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_06-300x230.jpg 300w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/><\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>5.7.\u00a0 EL MODELO COLEGIAL<\/h2>\n<p>Esta es otra \u00abestructura aparente\u00bb, como la  anterior, ya que lo  \u00fanico que incorpora es el concepto de comit\u00e9 o de la  adopci\u00f3n de  decisiones y del trabajo basado en el grupo. Forma de actuaci\u00f3n que   facilita los problemas de coordinaci\u00f3n de los modelos anteriores. La   incorporaci\u00f3n de los comit\u00e9s o grupos de trabajo puede ser tanto para  funciones  decisorias, como informativas y de apoyo a la estructura  organizativa b\u00e1sica.<\/p>\n<p>En definitiva, suele ser una \u00abestructura\u00bb  complementaria a los  modelos anteriores, especialmente generalizada en los  cl\u00e1sicos modelos  l\u00edneo-funcionales.<\/p>\n<p>Los mayores inconvenientes de esta forma estructural  son: la  tendencia a transigir y negociar entre los part\u00edcipes, una cierta   lentitud en la toma de decisiones en entornos din\u00e1micos y una posible  falta de  iniciativa en el papel de los directivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La combinaci\u00f3n de los principios antes expuestos y el mayor o menor \u00e9nfasis de los mismos permitir\u00e1n dise\u00f1ar unos modelos o formas espec\u00edficas de la estructura de organizaci\u00f3n. Un resumen de las formas principales se recoge en la tabla 4, abordando los modelos simples y complejos cl\u00e1sicos, as\u00ed como, algunos modelos nuevos de la organizaci\u00f3n&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1051,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-207","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5. Modelos b\u00e1sicos de organizaci\u00f3n - Blog de ADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5. Modelos b\u00e1sicos de organizaci\u00f3n - Blog de ADE\" \/>\n<meta property=\"og:description\" content=\"La combinaci\u00f3n de los principios antes expuestos y el mayor o menor \u00e9nfasis de los mismos permitir\u00e1n dise\u00f1ar unos modelos o formas espec\u00edficas de la estructura de organizaci\u00f3n. Un resumen de las formas principales se recoge en la tabla 4, abordando los modelos simples y complejos cl\u00e1sicos, as\u00ed como, algunos modelos nuevos de la organizaci\u00f3n....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/\",\"name\":\"5. Modelos b\u00e1sicos de organizaci\u00f3n - Blog de ADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/02_05_01.jpg\",\"datePublished\":\"2010-12-29T09:05:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/02_05_01.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/02_05_01.jpg\",\"width\":252,\"height\":244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/5-modelos-basicos-de-organizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libros\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Introducci\u00f3n a la Organizaci\u00f3n de Empresas\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Unidad did\u00e1ctica 2. El sistema de direcci\u00f3n y organizaci\u00f3n: principios y modelos organizativos\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/libros\\\/introduccion-a-la-organizacion-de-empresas-2\\\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"5. Modelos b\u00e1sicos de organizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"width\":940,\"height\":106,\"caption\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5. Modelos b\u00e1sicos de organizaci\u00f3n - Blog de ADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/","og_locale":"es_ES","og_type":"article","og_title":"5. Modelos b\u00e1sicos de organizaci\u00f3n - Blog de ADE","og_description":"La combinaci\u00f3n de los principios antes expuestos y el mayor o menor \u00e9nfasis de los mismos permitir\u00e1n dise\u00f1ar unos modelos o formas espec\u00edficas de la estructura de organizaci\u00f3n. Un resumen de las formas principales se recoge en la tabla 4, abordando los modelos simples y complejos cl\u00e1sicos, as\u00ed como, algunos modelos nuevos de la organizaci\u00f3n....","og_url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/","og_site_name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","og_image":[{"url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/","name":"5. Modelos b\u00e1sicos de organizaci\u00f3n - Blog de ADE","isPartOf":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/#primaryimage"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg","datePublished":"2010-12-29T09:05:38+00:00","breadcrumb":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/#primaryimage","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/02_05_01.jpg","width":252,"height":244},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/5-modelos-basicos-de-organizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/"},{"@type":"ListItem","position":2,"name":"Libros","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/"},{"@type":"ListItem","position":3,"name":"Introducci\u00f3n a la Organizaci\u00f3n de Empresas","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/"},{"@type":"ListItem","position":4,"name":"Unidad did\u00e1ctica 2. El sistema de direcci\u00f3n y organizaci\u00f3n: principios y modelos organizativos","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/libros\/introduccion-a-la-organizacion-de-empresas-2\/unidad-didactica-2-el-sistema-de-direccion-y-organizacion-principios-y-modelos-organizativos\/"},{"@type":"ListItem","position":5,"name":"5. Modelos b\u00e1sicos de organizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","description":"","publisher":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","width":940,"height":106,"caption":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/comments?post=207"}],"version-history":[{"count":0,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/207\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/1051"}],"wp:attachment":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/media?parent=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}