{"id":1943,"date":"2016-07-15T11:49:31","date_gmt":"2016-07-15T11:49:31","guid":{"rendered":"http:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?page_id=1943"},"modified":"2016-07-15T11:50:27","modified_gmt":"2016-07-15T11:50:27","slug":"9-2-prestamo-frances-fraccionado-html","status":"publish","type":"page","link":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/","title":{"rendered":"9.2. Pr\u00e9stamo franc\u00e9s fraccionado"},"content":{"rendered":"<p>Al ser un pr\u00e9stamo fraccionado los intereses se har\u00e1n efectivos fraccionadamente dentro del per\u00edodo de amortizaci\u00f3n, mientras que las cuotas de amortizaci\u00f3n no se fraccionan y se abonan al final del per\u00edodo.<\/p>\n<p>Considerando que el importe del pr\u00e9stamo es C<sub>0<\/sub>, y el tipo de inter\u00e9s constante es ik, expresado en la unidad de tiempo en la que se pagan los intereses, durante n per\u00edodos, caben dos posibilidades de llevar a cabo el fraccionamiento en este tipo de pr\u00e9stamos:<\/p>\n<ul>\n<li> Resultando constante el t\u00e9rmino amortizativo \u00fanico equivalente que se situar\u00eda en el momento de las amortizaciones.<\/li>\n<li> Siendo constante la cuant\u00eda total satisfecha en el momento de amortizar (tanto por amortizaci\u00f3n como por intereses).<\/li>\n<\/ul>\n<h3>9.2.1.<br \/>\n  Resultando constante el t\u00e9rmino amortizativo \u00fanico equivalente que se situar\u00eda en el momento de las amortizaciones<\/h3>\n<p> En este caso, al tratarse de un sistema franc\u00e9s y dado que el fraccionamiento s\u00f3lo afecta a los intereses, se trata de calcular en primer lugar las cuotas de amortizaci\u00f3n (que se obtienen con las reglas vistas anteriormente para el caso del pr\u00e9stamo franc\u00e9s, sin fraccionamiento), a continuaci\u00f3n los capitales pendientes y, finalmente, los intereses y t\u00e9rminos amortizativos. <\/p>\n<p class=\"progress\">Pasos a seguir:<\/p>\n<p> 1.\u00ba A partir del tipo de inter\u00e9s de partida calcular el tanto efectivo equivalente expresado en la unidad de tiempo en la que se amortiza el capital.<\/p>\n<p>i = (1 + i<sub>k<\/sub>)<sup>k<\/sup> \u2013 1<\/p>\n<p> 2.\u00ba C\u00e1lculo de la primera cuota de amortizaci\u00f3n, siguiendo las f\u00f3rmulas empleadas en el pr\u00e9stamo franc\u00e9s cuando no existe fraccionamiento de intereses, puesto que dicho fraccionamiento s\u00f3lo afecta a los intereses pero no a las cuotas de amortizaci\u00f3n que se siguen calculando de la misma forma.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-01.png\" width=\"237\" height=\"69\" \/><\/p>\n<p>siendo n el n\u00famero de cuotas de principal con las que amortizamos el pr\u00e9stamo.<\/p>\n<p> 3.\u00ba C\u00e1lculo del resto de cuotas de amortizaci\u00f3n, que variar\u00e1n en progresi\u00f3n geom\u00e9trica creciente de raz\u00f3n (1 + i).<\/p>\n<p>A<sub>t+1<\/sub>  =  A<sub>t<\/sub>  x  (1  +  i)  =  A<sub>1<\/sub>  x  (1  +  i)<sup>t<\/sup><\/p>\n<p> 4.\u00ba C\u00e1lculo del total amortizado, mt, por sumas parciales de las cuotas de amortizaci\u00f3n, que se pueden calcular una a una y sum\u00e1ndose posteriormente, o bien, se pueden sumar directamente a trav\u00e9s de la ley que siguen:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-02.png\" width=\"332\" height=\"29\" \/><\/p>\n<p> 5.\u00ba C\u00e1lculo del capital vivo, C<sub>t<\/sub>, restando al capital pendiente del per\u00edodo anterior la cuota de amortizaci\u00f3n del per\u00edodo en curso o bien restando al importe del pr\u00e9stamo el total amortizado hasta el momento:<\/p>\n<p>C<sub>t<\/sub> =  C<sub>t-1<\/sub> &#8211;  A<sub>t<\/sub> =  C<sub>0<\/sub> &#8211;  m<sub>t<\/sub><\/p>\n<p> 6.\u00ba C\u00e1lculo de las cuotas de inter\u00e9s, I<sub>t+1<\/sub>, que se pagar\u00e1n con la frecuencia acordada y siempre a partir del capital pendiente a principios del per\u00edodo a que se refiera empleando el tanto efectivo expresado en la unidad en la que se est\u00e9n pagando los intereses (i<sub>k<\/sub>). <\/p>\n<p>I<sub>t+1<\/sub>  =  C<sub>t<\/sub>  x  i<sub>k<\/sub><\/p>\n<p> 7.\u00ba C\u00e1lculo de los t\u00e9rminos amortizativos, por suma de lo que en cada subper\u00edodo se est\u00e9 pagando: siempre intereses y en el \u00faltimo de cada per\u00edodo, adem\u00e1s, cuota de amortizaci\u00f3n.<\/p>\n<ul>\n<li> Los primeros k\u20131 subper\u00edodos (s\u00f3lo intereses):\n<p>a<sub>t, j<\/sub>  =  I<sub>t+1<\/sub> <\/p>\n<\/li>\n<li> El \u00faltimo subper\u00edodo (inter\u00e9s y amortizaci\u00f3n):\n<p>a<sub>t, k<\/sub>  =  I<sub>t+1<\/sub>  +  A<sub>t<\/sub><\/p>\n<\/li>\n<\/ul>\n<p> Otro camino alternativo, v\u00e1lido para este tipo de pr\u00e9stamos, consiste en calcular el t\u00e9rmino amortizativo anual equivalente para, a partir del mismo, calcular los capitales vivos, las cuotas de inter\u00e9s y finalmente las cuotas de amortizaci\u00f3n y los t\u00e9rminos amortizativos en cada momento.<\/p>\n<p class=\"progress\">Pasos a seguir:<\/p>\n<p> 1.\u00ba A partir del tipo de inter\u00e9s de partida calcular el tanto efectivo equivalente expresado en la unidad de tiempo en la que se amortiza el capital.<\/p>\n<p>i  =  (1  +  i<sub>k<\/sub>)<sup>k<\/sup>  &#8211;  1<\/p>\n<p> 2.\u00ba C\u00e1lculo del t\u00e9rmino amortizativo equivalente, siguiendo las f\u00f3rmulas empleadas en el pr\u00e9stamo franc\u00e9s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p289-01.png\" width=\"123\" height=\"40\" \/><\/p>\n<p> 3.\u00ba C\u00e1lculo del capital pendiente a principios del per\u00edodo t + 1.<\/p>\n<p> <span class=\"progress\">M\u00e9todo retrospectivo<\/span>, a trav\u00e9s de los t\u00e9rminos amortizativos pasados.<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p289-02.png\" width=\"276\" height=\"35\" \/><\/p>\n<p><span class=\"progress\">M\u00e9todo prospectivo<\/span>, a trav\u00e9s de los t\u00e9rminos amortizativos futuros.<\/p>\n<p> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p289-03.png\" width=\"176\" height=\"29\" \/><\/p>\n<p> 4.\u00ba C\u00e1lculo de las cuotas de inter\u00e9s pagadas dentro del per\u00edodo t + 1.<\/p>\n<p>Los intereses de cualquier subper\u00edodo se calcular\u00e1n a partir de la deuda pendiente a principios de ese per\u00edodo, al tanto efectivo fraccionado vigente durante el mismo.<\/p>\n<p>I<sub>t+1<\/sub>  =  C<sub>t  <\/sub>x  i<sub>k<\/sub><\/p>\n<p>5.\u00ba C\u00e1lculo de la cuota de amortizaci\u00f3n del per\u00edodo t + 1<\/p>\n<p> Se debe mantener la equivalencia financiera entre el t\u00e9rmino amortizativo equivalente calculado inicialmente y los pagos que realmente tienen lugar dentro del per\u00edodo, las k cuotas de inter\u00e9s k-esimal y la cuota de amortizaci\u00f3n satisfecha a final del per\u00edodo. Por tanto, el t\u00e9rmino amortizativo equivalente, al final del per\u00edodo, debe coincidir con las cuotas de inter\u00e9s (conocidas) del per\u00edodo llevadas al final de dicho per\u00edodo m\u00e1s la cuota de amortizaci\u00f3n (que se desconoce). De esa equivalencia se obtendr\u00e1 la cuota de amortizaci\u00f3n del per\u00edodo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p290-01.png\" width=\"501\" height=\"288\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p290-02.png\" width=\"188\" height=\"36\" \/><\/p>\n<p> De donde se despejar\u00eda A<sub>t+1<\/sub>.<\/p>\n<p> El resto de cuotas de amortizaci\u00f3n se puede obtener de la misma forma, para cada per\u00edodo o bien, siguiendo la ley de recurrencia que mantienen (en progresi\u00f3n geom\u00e9trica de raz\u00f3n 1 + i).<\/p>\n<p>6.\u00ba C\u00e1lculo de los t\u00e9rminos amortizativos, por suma de lo que en cada subper\u00edodo se est\u00e9 pagando: siempre intereses y en el \u00faltimo de cada per\u00edodo, adem\u00e1s, cuota de amortizaci\u00f3n.<\/p>\n<ul>\n<li> Los primeros k\u20131 subper\u00edodos (s\u00f3lo intereses):\n<p>a<sub>t, j<\/sub>  =  I<sub>t+1<\/sub><\/p>\n<\/li>\n<li> El \u00faltimo subper\u00edodo (intereses y amortizaci\u00f3n):\n<p>a<sub>t, k<\/sub>  =  I<sub>t+1<\/sub>  +  A<sub>t<\/sub><\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 10 <\/strong><\/p>\n<p>Construir el cuadro de amortizaci\u00f3n del siguiente pr\u00e9stamo:<\/p>\n<ul>\n<li> Importe: 1.000.000 de euros.<\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Sistema franc\u00e9s:<br \/>\n      \u2013 Cuotas de amortizaci\u00f3n anuales.<br \/>\n      \u2013 Intereses semestrales al 5% efectivo semestral.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p291-01.png\" width=\"485\" height=\"243\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>I<sub>1,1<\/sub>  =  I<sub>1,2<\/sub>  =  C<sub>0<\/sub>  x  0,05<br \/>\n      I<sub>2,1<\/sub>  =  I<sub>2,2<\/sub>  =  C<sub>1<\/sub>  x  0,05<br \/>\n      I<sub>3,1<\/sub>  =  I<sub>3,2<\/sub>  =  C<sub>2<\/sub>  x  0,05<\/p>\n<p> i  =  1,05<sup>2<\/sup> &#8211;   1  =  10,25%<\/p>\n<p>&nbsp;<\/p>\n<table width=\"512\" height=\"152\" border=\"1\" align=\"center\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td>\n<div align=\"center\">&nbsp;&nbsp;&nbsp;<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(3)\n      <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(4) <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(1) <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(2) <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">(5)<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\" class=\"progress\">Per&iacute;odos<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Capital<br \/>\n      vivo<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Cuota de inter\u00e9s <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Cuota de amortizaci\u00f3n<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Total amortizado <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">T\u00e9rminos amortizativos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1.1.<br \/>\n      1.2. <\/div>\n<\/td>\n<td>\n<div align=\"right\">1.000.000,00<br \/>\n      1.000.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\">50.000,00<br \/>\n      50.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <br \/>\n      301.385,81<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br \/>\n      301.385,81<\/div>\n<\/td>\n<td>\n<div align=\"right\">50.000,00<br \/>\n      351.385,81<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">2.1.<br \/>\n      2.2. <\/div>\n<\/td>\n<td>\n<div align=\"right\"> 698.614,19<br \/>\n      698.614,19<\/div>\n<\/td>\n<td>\n<div align=\"right\">34.930,71<br \/>\n      34.930,71<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <br \/>\n      332.277,86<\/div>\n<\/td>\n<td>\n<div align=\"right\">301.385,81<br \/>\n      633.663,67<\/div>\n<\/td>\n<td>\n<div align=\"right\">34.930,71<br \/>\n      367.208,57<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">3.1.<br \/>\n      3.2. <\/div>\n<\/td>\n<td>\n<div align=\"right\">366.336,33<br \/>\n      366.336,33<\/div>\n<\/td>\n<td>\n<div align=\"right\">18.316,82<br \/>\n      18.316,82<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <br \/>\n      366.336,33<\/div>\n<\/td>\n<td>\n<div align=\"right\">633.663,67<br \/>\n      1.000.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\">18.316,82<br \/>\n      384.653,15<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\"><span class=\"progress\">Total<\/span><\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\">&nbsp;<\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\">206.495,06 <\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\">1.000.000,00 <\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\">&nbsp;&nbsp;&nbsp;<\/div>\n<\/td>\n<td>\n<div align=\"right\"><span class=\"progress\">1.206.495,06<\/span><\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;  <\/p>\n<p><u><em>Descripci\u00f3n de los pasos a seguir para construir el cuadro:<\/em><\/u><\/p>\n<p> <span class=\"progress\">(1)<\/span>    Se calcula el importe de la primera cuota de amortizaci\u00f3n, a trav\u00e9s de la f\u00f3rmula prevista para calcular A1 en el pr\u00e9stamo franc\u00e9s, y, a partir de ella, todas las dem\u00e1s, multiplicando la cuota anterior por 1,1025.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p292-01.png\" width=\"376\" height=\"83\" \/><\/p>\n<p><span class=\"progress\">(2)<\/span>    Se calcula el total amortizado por sumas parciales de las cuotas de amortizaci\u00f3n practicadas hasta la fecha.<br \/>\n    <span class=\"progress\">(3)<\/span>    La deuda pendiente se obtendr\u00e1 de restar al capital a principios de cada per\u00edodo la cuota de amortizaci\u00f3n de ese mismo per\u00edodo, o bien, al importe del pr\u00e9stamo se le resta el total amortizado <span class=\"progress\">(2)<\/span> ya acumulado.<br \/>\n    <span class=\"progress\">(4)<\/span>    Las cuotas de inter\u00e9s se calculan sobre el capital pendiente a principios de cada per\u00edodo <span class=\"progress\">(3)<\/span> al tanto efectivo semestral.<br \/>\n    <span class=\"progress\">(5)<\/span>    El t\u00e9rmino amortizativo de cada per\u00edodo ser\u00e1 la suma de las columnas <span class=\"progress\">(1)<\/span> y <span class=\"progress\">(4)<\/span>.<\/p>\n<\/div>\n<p>&nbsp;  <\/p>\n<h3>9.2.2.<br \/>\nSiendo constante la cuant\u00eda satisfecha en el momento de amortizar (tanto por amortizaci\u00f3n como por intereses)<\/h3>\n<p class=\"progress\">Pasos a seguir:<\/p>\n<p> 1.\u00ba C\u00e1lculo de la ley de recurrencia entre cuotas de amortizaci\u00f3n consecutivas, de forma que resulte constante la cuant\u00eda total pagada al final de cada per\u00edodo. Para ello obligamos a que el pago total a efectuar al final de dos per\u00edodos consecutivos cualesquiera coincida:<\/p>\n<ul>\n<li> Pago total al final del per\u00edodo t:\n<p>A<sub>t<\/sub>  +  C<sub>t-1<\/sub>  x  i<sub>k<\/sub><\/p>\n<\/li>\n<li> Pago total al final del per\u00edodo t + 1:\n<p>A<sub>t+1<\/sub>  +  C<sub>t<\/sub>  x  i<sub>k<\/sub><\/p>\n<p>Obligando a que sean iguales ambas cuant\u00edas, resulta:<\/p>\n<p>A<sub>t<\/sub>  +  C<sub>t-1<\/sub>  x  i<sub>k<\/sub>  =  A<sub>t+1<\/sub>  +  C<sub>t<\/sub>  x  i<sub>k<\/sub><\/p>\n<\/li>\n<\/ul>\n<p> Operando en la igualdad, pasando Ct x ik al primer miembro:<\/p>\n<p>A<sub>t<\/sub>  +  C<sub>t-1<\/sub>  x  i<sub>k<\/sub>  &#8211;  C<sub>t<\/sub>  x  i<sub>k<\/sub>  =  A<sub>t+1<\/sub><\/p>\n<p>Sacando factor com\u00fan ik en el primer miembro:<\/p>\n<p>A<sub>t<\/sub>  +  (C<sub>t-1<\/sub>  &#8211;  C<sub>t<\/sub>)  x  i<sub>k<\/sub>  =  A<sub>t+1<\/sub><\/p>\n<p>Siendo:<\/p>\n<p>C<sub>t-1<\/sub>  &#8211;  C<sub>t<\/sub>  =  A<sub>t<\/sub><\/p>\n<p>Resulta finalmente:<\/p>\n<p>A<sub>t<\/sub>  +  A<sub>t<\/sub>  x  i<sub>k<\/sub>  =  A<sub>t+1<\/sub><\/p>\n<p>De donde se obtiene:<\/p>\n<p>A<sub>t+1<\/sub>  =  A<sub>t<\/sub>  x  (1  +  i<sub>k<\/sub>)<\/p>\n<p>Siendo ik el tanto al que se va a calcular los intereses a pagar en cada subper\u00edodo. <\/p>\n<p>Al aplicar esta ley para cualesquiera dos per\u00edodos consecutivos, se observa que var\u00edan siguiendo una progresi\u00f3n geom\u00e9trica de raz\u00f3n 1 + i<sub>k<\/sub>, por tanto, cualquier cuota se puede calcular a partir de la anterior, de la primera o de cualquiera conocida. Con car\u00e1cter gen\u00e9rico, se pondr\u00e1n en funci\u00f3n de la primera \u2013que es la m\u00e1s f\u00e1cil de obtener\u2013:<\/p>\n<p>A<sub>t+1<\/sub>  =  A<sub>1<\/sub>  x  (1  +  i<sub>k<\/sub>)<sup>t<\/sup><\/p>\n<p>2.\u00ba C\u00e1lculo de la primera cuota de amortizaci\u00f3n a trav\u00e9s de la siguiente expresi\u00f3n:<\/p>\n<p>En todo pr\u00e9stamo se cumple que la suma aritm\u00e9tica de todas las cuotas de amortizaci\u00f3n es el importe del pr\u00e9stamo:<\/p>\n<p>A<sub>1<\/sub>  +  A<sub>2<\/sub>  + A<sub>3<\/sub>  +  &#8230;  +  A<sub>n<\/sub>  =  C<sub>0<\/sub><\/p>\n<p>Adem\u00e1s, seg\u00fan la ley de recurrencia que siguen las cuotas de amortizaci\u00f3n, se pueden poner todas en funci\u00f3n de la primera de ellas:<\/p>\n<p>A<sub>1<\/sub>  +  A<sub>1<\/sub>  (1  +  i<sub>k<\/sub>)  +  A<sub>1<\/sub> (1  +  i<sub>k<\/sub>)<sup>2<\/sup>  +  &#8230;  +  A<sub>1<\/sub>  (1  +  i<sub>k<\/sub>)<sup>n-1<\/sup> =  C<sub>0<\/sub><\/p>\n<p>    Simplificando la expresi\u00f3n:<\/p>\n<p>A<sub>1<\/sub>  x  [1  +  (1  +  i<sub>k<\/sub>)  +  (1  +  i<sub>k<\/sub>)<sup>2<\/sup>  +  &#8230;  +  (1  +  i<sub>k<\/sub>)<sup>n-1<\/sup>]  =  C0<\/p>\n<p>Siendo el corchete el valor final de una renta unitaria, pospagable e inmediata de n t\u00e9rminos (el n\u00famero de cuotas de amortizaci\u00f3n), al tanto i<sub>k<\/sub> al que se calculan las cuotas de inter\u00e9s, por tanto:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p294-01.png\" width=\"127\" height=\"43\" \/><\/p>\n<p>De donde:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p294-02.png\" width=\"253\" height=\"68\" \/><\/p>\n<p>3.\u00ba C\u00e1lculo del resto de cuotas de amortizaci\u00f3n, que siguen como ley de recurrencia una progresi\u00f3n geom\u00e9trica de raz\u00f3n (1 + i<sub>k<\/sub>).<\/p>\n<p>A<sub>2<\/sub>  =  A<sub>1<\/sub>  x  (1  +  i<sub>k<\/sub>)<br \/>\n  A<sub>3<\/sub>  =  A<sub>2<\/sub>  x  (1  +  i<sub>k<\/sub>)  =  A<sub>1<\/sub>  x  (1  +  i<sub>k<\/sub>)<sup>2<br \/>\n  <\/sup>&#8230;<br \/>\n  A<sub>t+1<\/sub>  =  A<sub>t<\/sub>  x  (1  +  i<sub>k<\/sub>)  =  A<sub>1<\/sub>  x  (1  +  i<sub>k<\/sub>)<sup>t<\/sup><\/p>\n<p>4.\u00ba C\u00e1lculo del total amortizado, m<sub>t<\/sub>, por sumas parciales de las cuotas de amortizaci\u00f3n, ya practicadas.<\/p>\n<p>m<sub>t<\/sub>  =  A<sub>1<\/sub>  +  A<sub>2<\/sub>  +  &#8230;  +  A<sub>t<\/sub><\/p>\n<p>5.\u00ba C\u00e1lculo del capital vivo, C<sub>t<\/sub> , restando al capital pendiente del per\u00edodo anterior la cuota de amortizaci\u00f3n del per\u00edodo en curso o bien restando al importe del pr\u00e9stamo el total amortizado hasta el momento:<\/p>\n<p>C<sub>t<\/sub>  =  C<sub>t-1<\/sub>  &#8211;  A<sub>t<\/sub>  =  C<sub>0<\/sub>  &#8211;  m<sub>t<\/sub><\/p>\n<p> 6.\u00b0 C\u00e1lculo de la cuota de inter\u00e9s, I<sub>t+1<\/sub>, que se pagar\u00e1 con la frecuencia acordada y siempre a partir del capital pendiente a principios del per\u00edodo a que se refiera empleando el tanto efectivo expresado en la unidad en la que se est\u00e9n pagando los intereses (i<sub>k<\/sub>).<\/p>\n<p>I<sub>t+1<\/sub>  =  C<sub>t<\/sub>  x  i<sub>k<\/sub><\/p>\n<p> 7.\u00ba C\u00e1lculo de los t\u00e9rminos amortizativos, por suma de lo que en cada subper\u00edodo se est\u00e9 pagando: siempre intereses y en el \u00faltimo de cada per\u00edodo, adem\u00e1s, cuota de amortizaci\u00f3n.<\/p>\n<ul>\n<li> Los primeros k\u20131 subper\u00edodos (s\u00f3lo intereses):\n<p>a<sub>t, j<\/sub>  =  I<sub>t+1<\/sub><\/p>\n<\/li>\n<li> El \u00faltimo subper\u00edodo (inter\u00e9s y principal):\n<p>a<sub>t, k<\/sub>  =  I<sub>t+1<\/sub>  +  A<sub>t+1<\/sub><\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div class=\"ejemplo\">\n<p><strong>EJEMPLO 11<\/strong><\/p>\n<p>Construir el cuadro de amortizaci\u00f3n del siguiente pr\u00e9stamo:<\/p>\n<ul>\n<li> Importe: 1.000.000 de euros.<\/li>\n<li> Duraci\u00f3n: 3 a\u00f1os.<\/li>\n<li> Sistema franc\u00e9s:<br \/> <br \/>\n      \u2013 Cuotas de amortizaci\u00f3n anuales.<br \/>\n    \u2013 Intereses semestrales al 5% efectivo semestral.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p296-01.png\" width=\"446\" height=\"430\" \/><\/p>\n<p>&nbsp; <\/p>\n<p>Se ha de cumplir:<\/p>\n<p>A<sub>1<\/sub>  +  C<sub>0<\/sub>  x  0,05  =  A<sub>2<\/sub>  +  C<sub>1<\/sub>  x  0,05  =  A<sub>3<\/sub>  +  C<sub>2<\/sub>  x  0,05<\/p>\n<p>&nbsp;<\/p>\n<table width=\"508\" height=\"152\" border=\"1\" align=\"center\" cellpadding=\"0\" cellspacing=\"0\">\n<tr>\n<td width=\"58\">\n<div align=\"center\"><\/div>\n<\/td>\n<td width=\"84\">\n<div align=\"center\" class=\"progress\">(3)\n      <\/div>\n<\/td>\n<td width=\"92\">\n<div align=\"center\" class=\"progress\">(4) <\/div>\n<\/td>\n<td width=\"110\">\n<div align=\"center\" class=\"progress\">(1) <\/div>\n<\/td>\n<td width=\"84\">\n<div align=\"center\" class=\"progress\">(2) <\/div>\n<\/td>\n<td width=\"128\">\n<div align=\"center\" class=\"progress\">(5)<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\" class=\"progress\">Per&iacute;odos<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Capital<br \/>\n      vivo<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Cuota de inter\u00e9s <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Cuota de amortizaci\u00f3n<\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">Total amortizado <\/div>\n<\/td>\n<td>\n<div align=\"center\" class=\"progress\">T\u00e9rminos amortizativos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">1.1.<br \/>\n      1.2. <\/div>\n<\/td>\n<td>\n<div align=\"right\">1.000.000,00<br \/>\n      1.000.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\">50.000,00<br \/>\n      50.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 <br \/>\n      317.208,56<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013<br \/>\n      317.208,56<\/div>\n<\/td>\n<td>\n<div align=\"right\">50.000,00<br \/>\n      367.208,56<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">2.1.<br \/>\n      2.2. <\/div>\n<\/td>\n<td>\n<div align=\"right\">682.791,44<br \/>\n      682.791,44<\/div>\n<\/td>\n<td>\n<div align=\"right\">34.139,57<br \/>\n      34.139,57<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 <br \/>\n      333.069,00 <\/div>\n<\/td>\n<td>\n<div align=\"right\">317.208,56<br \/>\n      650.277,56<\/div>\n<\/td>\n<td>\n<div align=\"right\">34.139,56<br \/>\n      367.208,56<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\">3.1.<br \/>\n      3.2. <\/div>\n<\/td>\n<td>\n<div align=\"right\">349.722,44<br \/>\n      349.722,44<\/div>\n<\/td>\n<td>\n<div align=\"right\">17.486,12<br \/>\n      17.486,12<\/div>\n<\/td>\n<td>\n<div align=\"right\">\u2013 <br \/>\n      349.722,44<\/div>\n<\/td>\n<td>\n<div align=\"right\">650.277,56<br \/>\n      1.000.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\">17.486,12<br \/>\n      367.208,56<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<div align=\"center\"><span class=\"progress\">Total<\/span><\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\"><\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\"> 203.251,38 <\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\">1.000.000,00<\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\"><\/div>\n<\/td>\n<td>\n<div align=\"right\" class=\"progress\">1.203.251,38<\/div>\n<\/td>\n<\/tr>\n<\/table>\n<p>\n  <\/p>\n<p><u><em>Descripci\u00f3n de los pasos a seguir para construir el cuadro:<\/em><\/u><\/p>\n<p> <span class=\"progress\">(1) <\/span>Se calcula el importe de la primera cuota de amortizaci\u00f3n, a trav\u00e9s de la f\u00f3rmula correspondiente, y, a partir de ella, todas las dem\u00e1s, multiplicando la cuota anterior por 1,05.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p297-01.png\" width=\"361\" height=\"55\" \/><\/p>\n<p><span class=\"progress\">(2)<\/span>    Se calcula el total amortizado por sumas parciales de las cuotas de amortizaci\u00f3n practicadas hasta la fecha.<br \/>\n    <span class=\"progress\">(3)<\/span>    La deuda pendiente se obtendr\u00e1 de restar al capital a principios de cada per\u00edodo la cuota de amortizaci\u00f3n de ese mismo per\u00edodo, o bien, al importe del pr\u00e9stamo se le resta el total amortizado <span class=\"progress\">(2)<\/span> ya acumulado.<br \/>\n    <span class=\"progress\">(4)<\/span>    Las cuotas de inter\u00e9s se calculan sobre el capital pendiente a principios de cada per\u00edodo <span class=\"progress\">(3)<\/span> al tanto efectivo semestral.<br \/>\n    <span class=\"progress\">(5)<\/span>    El t\u00e9rmino amortizativo de cada per\u00edodo ser\u00e1 la suma de las columnas <span class=\"progress\">(1)<\/span> y <span class=\"progress\">(4)<\/span>.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al ser un pr\u00e9stamo fraccionado los intereses se har\u00e1n efectivos fraccionadamente dentro del per\u00edodo de amortizaci\u00f3n, mientras que las cuotas de amortizaci\u00f3n no se fraccionan y se abonan al final del per\u00edodo. Considerando que el importe del pr\u00e9stamo es C0, y el tipo de inter\u00e9s constante es ik, expresado en la unidad de tiempo en&#8230;<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":4092,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1943","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>9.2. Pr\u00e9stamo franc\u00e9s fraccionado - Blog de ADE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9.2. Pr\u00e9stamo franc\u00e9s fraccionado - Blog de ADE\" \/>\n<meta property=\"og:description\" content=\"Al ser un pr\u00e9stamo fraccionado los intereses se har\u00e1n efectivos fraccionadamente dentro del per\u00edodo de amortizaci\u00f3n, mientras que las cuotas de amortizaci\u00f3n no se fraccionan y se abonan al final del per\u00edodo. Considerando que el importe del pr\u00e9stamo es C0, y el tipo de inter\u00e9s constante es ik, expresado en la unidad de tiempo en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-15T11:50:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-01.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/\",\"name\":\"9.2. Pr\u00e9stamo franc\u00e9s fraccionado - Blog de ADE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p287-01.png\",\"datePublished\":\"2016-07-15T11:49:31+00:00\",\"dateModified\":\"2016-07-15T11:50:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p287-01.png\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/images_book\\\/p287-01.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/9-2-prestamo-frances-fraccionado-html\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9.2. Pr\u00e9stamo franc\u00e9s fraccionado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#website\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#organization\",\"name\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/BANNER_ADE_940_V2.jpg\",\"width\":940,\"height\":106,\"caption\":\"Blog de ADE - Universidad a Distancia de Madrid | UDIMA\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.udima.es\\\/administracion-y-direccion-de-empresas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9.2. Pr\u00e9stamo franc\u00e9s fraccionado - Blog de ADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/","og_locale":"es_ES","og_type":"article","og_title":"9.2. Pr\u00e9stamo franc\u00e9s fraccionado - Blog de ADE","og_description":"Al ser un pr\u00e9stamo fraccionado los intereses se har\u00e1n efectivos fraccionadamente dentro del per\u00edodo de amortizaci\u00f3n, mientras que las cuotas de amortizaci\u00f3n no se fraccionan y se abonan al final del per\u00edodo. Considerando que el importe del pr\u00e9stamo es C0, y el tipo de inter\u00e9s constante es ik, expresado en la unidad de tiempo en...","og_url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/","og_site_name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","article_modified_time":"2016-07-15T11:50:27+00:00","og_image":[{"url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-01.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/","name":"9.2. Pr\u00e9stamo franc\u00e9s fraccionado - Blog de ADE","isPartOf":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/#primaryimage"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-01.png","datePublished":"2016-07-15T11:49:31+00:00","dateModified":"2016-07-15T11:50:27+00:00","breadcrumb":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/#primaryimage","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-01.png","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/images_book\/p287-01.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/9-2-prestamo-frances-fraccionado-html\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/"},{"@type":"ListItem","position":2,"name":"9.2. Pr\u00e9stamo franc\u00e9s fraccionado"}]},{"@type":"WebSite","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#website","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","description":"","publisher":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#organization","name":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/","url":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","contentUrl":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-content\/uploads\/2019\/10\/BANNER_ADE_940_V2.jpg","width":940,"height":106,"caption":"Blog de ADE - Universidad a Distancia de Madrid | UDIMA"},"image":{"@id":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/1943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/comments?post=1943"}],"version-history":[{"count":2,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/1943\/revisions"}],"predecessor-version":[{"id":1946,"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/pages\/1943\/revisions\/1946"}],"wp:attachment":[{"href":"https:\/\/blogs.udima.es\/administracion-y-direccion-de-empresas\/wp-json\/wp\/v2\/media?parent=1943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}